{"text_format":"1","workbook":"xlsx","n_sheets":43,"sheets":["LA Sheets","NOTES","Cairngorms Statement","Summary Data","Legacy Cases","Clock Stops","Glasgow Note","Charts_data -Annual","SCOTLAND","Aberdeen City","Aberdeenshire","Angus","Argyll and Bute","Cairngorms National Park","Clackmannanshire","Dumfries and Galloway","Dundee","East Ayrshire","East Dunbartonshire","East Lothian","East Renfrewshire","City of Edinburgh","Falkirk","Fife","Glasgow City","Highland","Inverclyde","Loch Lomond","Midlothian","Moray","Na h-Eileanan Siar","North Ayrshire","North Lanarkshire"," Orkney Islands","Perth and Kinross","Renfrewshire","Scottish Borders","Shetland Islands","South Ayrshire","South Lanarkshire","Stirling","West Dunbartonshire","West Lothian"],"not_rendered":{"charts":0,"images":0,"macros":1,"external_links":1,"defined_names":84,"comments":0,"pivot_tables":0},"unopened":[],"bounds":{"document_bytes":16777216,"sheet_cells":100000,"rows_first":2000,"rows_last":500,"rows_between":2000,"halvings":0,"cell_chars":16384,"cell_head_chars":4096},"cells_cut":0,"cells_raw":0,"read":"whole","date_system":"1900"}

{"sheet":"LA Sheets","index":0,"n_rows":46,"n_cols":2,"rows_kept":46,"cut":false,"hidden":false,"merged":[]}
[]
[null,"2018/19 Quarterly Planning Performance Statistics"]
[null,"Quarter 3"]
[null,"Published 23rd July 2019"]
[]
[null,"SCOTLAND"]
[null,"Aberdeen City"]
[null,"Aberdeenshire"]
[null,"Angus"]
[null,"Argyll and Bute"]
[null,"Cairngorms National Park"]
[null,"Clackmannanshire"]
[null,"Dumfries and Galloway"]
[null,"Dundee City"]
[null,"East Ayrshire"]
[null,"East Dunbartonshire"]
[null,"East Lothian"]
[null,"East Renfrewshire"]
[null,"City of Edinburgh"]
[null,"Falkirk"]
[null,"Fife"]
[null,"Glasgow City "]
[null,"Highland"]
[null,"Inverclyde"]
[null,"Loch Lomond and The Trossachs National Park"]
[null,"Midlothian"]
[null,"Moray"]
[null,"Na h-Eileanan Siar"]
[null,"North Ayrshire"]
[null,"North Lanarkshire"]
[null,"Orkney Islands"]
[null,"Perth and Kinross"]
[null,"Renfrewshire"]
[null,"Scottish Borders"]
[null,"Shetland Islands"]
[null,"South Ayrshire"]
[null,"South Lanarkshire"]
[null,"Stirling"]
[null,"West Dunbartonshire"]
[null,"West Lothian"]
[]
[null,"Notes"]
[null,"Cairngorms Statement"]
[null,"Summary Data"]
[null,"Legacy Cases"]
[null,"Clock Stops by Planning Authority"]

{"sheet":"NOTES","index":1,"n_rows":1,"n_cols":15,"rows_kept":1,"cut":false,"hidden":false,"merged":[]}
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Return to Contents"]

{"sheet":"Cairngorms Statement","index":2,"n_rows":1,"n_cols":13,"rows_kept":1,"cut":false,"hidden":false,"merged":[]}
[" ",null,null,null,null,null,null,null,null,null,null,null,"Return to Contents"]

{"sheet":"Summary Data","index":3,"n_rows":33,"n_cols":19,"rows_kept":33,"cut":false,"hidden":false,"merged":[[4,14,4,15],[13,7,13,8],[13,13,13,14],[13,9,13,10],[4,10,4,11],[4,8,4,9],[4,6,4,7],[13,5,13,6],[4,12,4,13],[4,1,4,3],[13,1,13,2],[13,11,13,12],[4,4,4,5],[13,3,13,4],[32,0,32,2],[22,1,22,3],[22,22,22,24],[22,19,22,21],[22,16,22,18],[22,13,22,15],[22,7,22,9],[22,10,22,12],[22,4,22,6]]}
["Summary Comparisons1"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Return to Contents"]
["Local Developments (excluding legacy cases)"]
[null,"Post 3 August 2009",null,null,null,null,null,null,null,null,null,null,"Return To Contents"]
[null,"Q3 - 2018/19",null,null,"Q2 - 2018/19",null,"Q1 - 2018/19",null,"Q4 - 2017/18",null,"Q3 - 2017/18",null,"Q2 - 2017/18"]
[null,"Applications","Overall Average (Weeks)","Percentage under 2 months","Overall Average (Weeks)","Percentage under 2 months","Overall Average (Weeks)","Percentage under 2 months","Overall Average (Weeks)","Percentage under 2 months","Overall Average (Weeks)","Percentage under 2 months","Overall Average (Weeks)","Percentage under 2 months"]
["All Local Developments2",6155,8.8390391087385414,0.76815597075548336,8.8265739415893218,0.7570518653321201,8.9026318002186162,0.7545615067686875,9.3284007801072644,0.72559726962457338,9.0985417394341574,0.7169926650366748,8.9737813653713783,0.74273616586362967]
["Householder",3044,6.9574338276703589,0.8810775295663601,7.2431426840875686,0.86129618413082976,7.2122389911101932,0.85933429811866857,7.622048459282885,0.82715160244868569,7.3454233833611262,0.82976653696498059,7.206294424586055,0.87489214840379637]
["Housing",1169,12.251863619699376,0.59794696321642427,12.066139817629177,0.58127659574468082,11.975780975780973,0.56511056511056512,11.960875160875162,0.58828828828828827,11.704140615783887,0.54252683732452522,12.783912588631875,0.51017087062652566]
["Business and Industry",372,9.2139016897081429,0.70161290322580649,8.9697305278700643,0.70025839793281652,8.5717866093805934,0.75939849624060152,9.4671389216843753,0.7024793388429752,10.183058147882267,0.6733668341708543,8.9380952380952383,0.70256410256410251]
[]
["Major Developments (excluding legacy cases)"]
[null,"Post 3 August 2009"]
[null,"Q3 - 2018/19",null,"Q2 - 2018/19",null,"Q1 - 2018/19",null,"Q4 - 2017/18",null,"Q3 - 2017/18",null,"Q2 - 2017/18"]
[null,"Applications","Overall Average (Weeks)","Applications","Overall Average (Weeks)","Applications","Overall Average (Weeks)","Applications","Overall Average (Weeks)","Applications","Overall Average (Weeks)","Applications","Overall Average (Weeks)"]
["All Major developments2",58,26.455665024630544,57,37.719298245614034,54,31.740740740740733,63,34.775510204081634,63,27.673469387755105,57,32.799999999999997]
["Housing",28,30.02551020408163,28,39.005102040816318,24,34.642857142857146,33,38.112554112554115,31,33.8110599078341,22,36.402597402597401]
["Business and Industry",8,13.375000000000002,2,12.571428571428571,8,24.357142857142858,7,21.510204081632651,6,33.976190476190474,0,0]
[]
[]
["Legal Agreements Comparison3"]
[null,"Post 3 August 2009"]
[null,"Q3 - 2018/19",null,null,"Q2 - 2018/19",null,null,"Q1 - 2018/19",null,null,"Q4 - 2017/18",null,null,"Q3 - 2017/18",null,null,"Q2 - 2017/18"]
[null,"Without Legal Agreements  (weeks)","With Legal Agreement  (weeks)","Overall Average (Weeks)","Without Legal Agreements  (weeks)","With Legal Agreement  (weeks)","Overall Average (Weeks)","Without Legal Agreements  (weeks)","With Legal Agreement  (weeks)","Overall Average (Weeks)","Without Legal Agreements  (weeks)","With Legal Agreement  (weeks)","Overall Average (Weeks)","Without Legal Agreements  (weeks)","With Legal Agreement  (weeks)","Overall Average (Weeks)","Without Legal Agreements  (weeks)","With Legal Agreement  (weeks)","Overall Average (Weeks)"]
["All Local4",8.4362127339415025,39.820976491862567,8.8390391087385414,8.5676202149313863,34.053304904051174,8.8265739416785838,8.6685578292003989,30.459882583170259,8.9026318002186162,8.9165020847048471,32.138832997987926,9.1670393123059881,9.0132453604171285,32.390596745027125,9.3284007801072644,8.9598193633660088,24.346246973365616,9.098541739434161]
["All Major",19.653571428571428,41.571428571428569,26.455665024630544,27.703832752613241,63.383928571428562,37.719298245614034,19.68571428571429,46.809523809523803,31.740740740740733,25.580086580086579,44.163265306122454,34.110070257611241,26.064285714285717,49.925465838509311,34.775510204081634,20.516483516483518,39.303571428571423,27.673469387755105]
[]
[]
[]
["1. Excludes Other Consents, Local developments with Environmental Impact Assessments, and applications with processing agreements."]
["2. Overall averages per quarter will be affected by the volumes of different case-types that happen to be decided on in that quarter."]
["3. Excludes legacy cases and applications with legal agreements that also had a processing agreement."]
["4. 2018/19 Q1/Q2 figures were revised on 23 July 2019."]

{"sheet":"Legacy Cases","index":4,"n_rows":19,"n_cols":9,"rows_kept":19,"cut":false,"hidden":false,"merged":[]}
["Legacy Cases (pre-3rd August 2009)",null,null,null,null,null,"2018/19 Quarter 3",null,"Return to Contents"]
[]
["The following tables show details of applications that were validated pre-3rd August 2009 and so were originally subject to a previous reporting system."]
[]
["Legacy cases by planning authority - applications with processing agreements",null,null,null," Legacy cases by development type - applications with processing agreements"]
["Local Authority","Number of Legacy Cases","% meeting agreed timescales",null,"Development Type","Number of Legacy Cases","% meeting agreed timescales"]
["None",0,"-",null,"None",0,"-"]
[]
["Total",null,null,null,"Total "]
[]
["Legacy cases by planning authority - applications without  processing agreements",null,null,null," Legacy cases by development type - applications without processing agreements"]
["Local Authority","Number of Legacy Cases","Average Decision Time (weeks)",null,"Development Type","Number of Legacy Cases","Average Decision Time (weeks)"]
["East Lothian1",2,59.142857142857146,null,"Housing - Local1",1,299.28571428571428]
["City of Edinburgh1",1,299.28571428571428,null,"Other Developments - Major1",1,129.42857142857142]
["Falkirk1",1,129.42857142857142,null,"Other Developments - Local1",1,58]
["Total",4,136.75,null,"Listed Building Consents1",1,60.285714285714285]
[null,null,null,null,"Total ",4,136.75]
[]
["1. These legacy cases had time removed from the decision time calculation where delays were caused by the applicant or external consultees, outwith the planning authority’s control."]

{"sheet":"Clock Stops","index":5,"n_rows":41,"n_cols":6,"rows_kept":41,"cut":false,"hidden":false,"merged":[]}
["Clock Stops by Planning Authority1,2",null,null,null,"2018/19 Quarter 3"]
[]
["Planning Authority","Total applications decided in 2018/19 Q3","Number of applications with clock stopped","Percentage of applications with clock stopped","Average length of time clock stopped (weeks)"]
["Aberdeen City",188,8,{"$f":"IF(B4=0, \"-\",C4/B4)","v":4.2553191489361701E-2},38.25]
["Aberdeenshire",489,4,{"$f":"IF(B5=0, \"-\",C5/B5)","v":8.1799591002044997E-3},3.8928571428571428]
["Angus",154,null,0,0]
["Argyll and Bute",329,16,4.8632218844984802E-2,16.803571428571427]
["Cairngorms National Park",1,null,0,0]
["Clackmannanshire",63,1,1.5873015873015872E-2,3.1428571428571428]
["Dumfries and Galloway",296,15,5.0675675675675678E-2,31.266666666666669]
["Dundee City",178,7,3.9325842696629212E-2,30.489795918367346]
["East Ayrshire ",125,15,0.12,9]
["East Dunbartonshire",193,40,0.20725388601036268,4.2178571428571425]
["East Lothian ",295,21,7.1186440677966104E-2,7.5714285714285712]
["East Renfrewshire",159,3,1.8867924528301886E-2,17.571428571428573]
["City of Edinburgh",755,2,2.6490066225165563E-3,148.07142857142858]
["Falkirk",139,5,3.5971223021582732E-2,8.3428571428571434]
["Fife",395,10,2.5316455696202531E-2,5.2142857142857144]
["Glasgow City",661,88,0.13313161875945537,10.355519480519479]
["Highland",746,35,4.6916890080428951E-2,26.248979591836733]
["Inverclyde",78,5,6.4102564102564097E-2,17.228571428571428," "]
["Loch Lomond and The Trossachs National Park",72,25,0.34722222222222221,16.725714285714286]
["Midlothian",152,12,7.8947368421052627E-2,10.035714285714286]
["Moray",157,37,0.2356687898089172,8.4826254826254832]
["Na h-Eileanan Siar",99,null,0,0]
["North Ayrshire",127,6,4.7244094488188976E-2,8.5476190476190474]
["North Lanarkshire",197,4,2.030456852791878E-2,27.535714285714285]
["Orkney Islands",115,21,0.18260869565217391,7.6666666666666661]
["Perth and Kinross",415,15,3.614457831325301E-2,14.904761904761903]
["Renfrewshire",160,18,0.1125,10.142857142857142]
["Scottish Borders",192,1,5.208333333333333E-3,3]
["Shetland Islands",67,10,0.14925373134328357,5.8999999999999995]
["South Ayrshire",216,null,0,0]
["South Lanarkshire",350,8,2.2857142857142857E-2,30.053571428571427]
["Stirling",196,1,5.1020408163265302E-3,23.428571428571427]
["West Dunbartonshire",58,17,0.29310344827586204,7.6974789915966388]
["West Lothian2",196,13,6.6326530612244902E-2,16.802197802197803," "]
["SCOTLAND",8013,{"$f":"SUM(C4:C37)","v":463},5.7781105703232249E-2,13.722925023141006," "]
["1. Processing Agreements are not included in this analysis."]
["2. Legacy cases are not included in this analysis",null,null,null," "]
[null," "]

{"sheet":"Glasgow Note","index":6,"n_rows":0,"n_cols":0,"rows_kept":0,"cut":false,"hidden":true,"merged":[]}

{"sheet":"Charts_data -Annual","index":7,"n_rows":547,"n_cols":10,"rows_kept":547,"cut":false,"hidden":true,"merged":[[467,0,470,0],[490,0,493,0],[517,0,520,0],[543,0,546,0],[362,0,365,0],[389,0,392,0],[413,0,416,0],[440,0,443,0],[339,0,342,0],[526,0,526,1],[527,0,530,0],[535,0,538,0],[531,0,534,0],[539,0,542,0],[500,0,500,1],[501,0,504,0],[505,0,508,0],[509,0,512,0],[513,0,516,0],[473,0,473,1],[474,0,477,0],[478,0,481,0],[482,0,485,0],[486,0,489,0],[168,0,171,0],[192,0,195,0],[143,0,146,0],[117,0,120,0],[67,0,70,0],[91,0,94,0],[43,0,46,0],[234,0,237,0],[188,0,191,0],[198,0,198,1],[199,0,202,0],[203,0,206,0],[207,0,210,0],[164,0,167,0],[175,0,175,1],[176,0,179,0],[180,0,183,0],[184,0,187,0],[139,0,142,0],[151,0,151,1],[152,0,155,0],[156,0,159,0],[160,0,163,0],[113,0,116,0],[463,0,466,0],[450,0,450,1],[451,0,454,0],[455,0,458,0],[459,0,462,0],[436,0,439,0],[409,0,412,0],[423,0,423,1],[424,0,427,0],[428,0,431,0],[432,0,435,0],[385,0,388,0],[396,0,396,1],[397,0,400,0],[401,0,404,0],[405,0,408,0],[358,0,361,0],[372,0,372,1],[373,0,376,0],[377,0,380,0],[381,0,384,0],[335,0,338,0],[345,0,345,1],[346,0,349,0],[350,0,353,0],[354,0,357,0],[308,0,311,0],[322,0,322,1],[323,0,326,0],[327,0,330,0],[331,0,334,0],[284,0,287,0],[304,0,307,0],[295,0,295,1],[296,0,299,0],[300,0,303,0],[288,0,291,0],[312,0,315,0],[260,0,263,0],[271,0,271,1],[272,0,275,0],[276,0,279,0],[280,0,283,0],[247,0,247,1],[248,0,251,0],[252,0,255,0],[256,0,259,0],[264,0,267,0],[211,0,214,0],[221,0,221,1],[222,0,225,0],[226,0,229,0],[230,0,233,0],[215,0,218,0],[238,0,241,0],[126,0,126,1],[135,0,138,0],[127,0,130,0],[131,0,134,0],[100,0,100,1],[109,0,112,0],[101,0,104,0],[105,0,108,0],[83,0,86,0],[79,0,82,0],[75,0,78,0],[87,0,90,0],[2,0,5,0],[10,0,13,0],[6,0,9,0],[14,0,17,0],[27,0,30,0],[59,0,62,0],[63,0,66,0],[31,0,34,0],[35,0,38,0],[51,0,54,0],[55,0,58,0],[39,0,42,0],[18,0,21,0]]}
["Chart 5: Local Development Planning Applications -  Number of decisions"]
[null,null,"Number of decisions"]
["2012/13","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2013/14","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2014/15","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2015/16","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2016/17","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[]
[]
[]
["Chart 6: Local Development Planning Applications -  Average decision time (weeks)"]
[null,null,"Average decision time"]
["2012/13","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2013/14","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2014/15","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2015/16","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2016/17","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[]
[]
["Chart 7: Major Development Planning Applications -  Number of decisions"]
[null,null,"Number of decisions"]
["2012/13","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2013/14","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2014/15","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2015/16","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2016/17","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[]
[]
["Chart 8: Major Development Planning Applications -  Average decision time (weeks"]
[null,null,"Average decision time"]
["2012/13","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2013/14","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2014/15","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2015/16","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2016/17","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}}]
[]
[]
[]
[]
["Chart 21: All Local Development Planning Applications -  Number of decisions "]
["Year/ Quarter",null,"All Applications","Post-August 2009"]
["2012/13","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2013/14","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2014/15","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2015/16","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2016/17","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[]
[]
[]
[]
["Chart 22: All Local Development Planning Applications -  Average decision time (weeks)"]
["Year/ Quarter",null,"All Applications","Post-August 2009"]
["2012/13","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2013/14","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2014/15","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2015/16","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2016/17","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[]
[]
[]
["Chart 23: Householder developments -  Number of decisions"]
["Year/ Quarter",null,"All Applications","Post-August 2009"]
["2012/13","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2013/14","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2014/15","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2015/16","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2016/17","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[]
[]
["Chart 24: Householder developments -  Average decision time (weeks)"]
["Year/ Quarter",null,"All Applications","Post-August 2009"]
["2012/13","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2013/14","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2014/15","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2015/16","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2016/17","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[]
["Chart 25: Local Housing developments -  Number of decisions"]
["Year/ Quarter",null,"All Applications","Post-August 2009"]
["2012/13","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2013/14","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2014/15","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2015/16","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2016/17","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[]
["Chart 26: Local Housing developments -  Average decision time (weeks)"]
["Year/ Quarter",null,"All Applications","Post-August 2009"]
["2012/13","Q1",24.870448179271705,18.275097917955058]
[null,"Q2",20.058038896242742,16.879064935064935]
[null,"Q3",18.436985912829723,16.001341381623071]
[null,"Q4",20.445127030403995,17.796265034817466]
["2013/14","Q1",17.75521845851743,15.326477918452801]
[null,"Q2",18.53038202673239,15.592549923195083]
[null,"Q3",16.666171666171667,14.779974044124986]
[null,"Q4",16.910375939849622,15.031329210179457]
["2014/15","Q1",15.648944805194805,15.312271062271064]
[null,"Q2",15.408070500927645,14.283660130718955]
[null,"Q3",14.068930421909695,13.922962825623433]
[null,"Q4",16.158907312925173,14.452273702273706]
["2015/16","Q1",13.6,13.5]
[null,"Q2",14.357789945246392,13.106291324383893]
[null,"Q3",13.807703762533505,13.623802873104548]
[null,"Q4",16.2,14.6]
["2016/17","Q1",12.7,12.4]
[null,"Q2",13,12.6]
[null,"Q3",12.8,12.8]
[null,"Q4",12.809604043807919,12.809604043807919]
[]
[]
[]
[]
["Chart 27: Local Business and Industry developments -  Number of decisions"]
["Year/ Quarter",null,"All Applications","Post-August 2009"]
["2012/13","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2013/14","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2014/15","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2015/16","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2016/17","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[]
[]
["Chart 28: Local Business and Industry developments -  Average decision time (weeks)"]
["Year/ Quarter",null,"All Applications","Post-August 2009"]
["2012/13","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2013/14","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2014/15","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2015/16","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2016/17","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[]
[]
["Chart 29: All Major developments - Number of decisions"]
["Year/ Quarter",null,"All Applications","Post-August 2009"]
["2012/13","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2013/14","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2014/15","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2015/16","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2016/17","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[]
[]
[]
[]
[]
["Chart 30: All Major developments - Average decision time (weeks)"]
["Year/ Quarter",null,"All Applications","Post-August 2009"]
["2012/13","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2013/14","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2014/15","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2015/16","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2016/17","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[]
["Chart 31: Major Housing developments - Number of decisions"]
["Year/ Quarter",null,"All Applications","Post-August 2009"]
["2012/13","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2013/14","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}},null,null,null,null,null,2]
["2014/15","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2015/16","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2016/17","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[]
[]
[]
[]
[]
["Chart 32: Major Housing developments - Average decision time (weeks)"]
["Year/ Quarter",null,"All Applications","Post-August 2009"]
["2012/13","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2013/14","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2014/15","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2015/16","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2016/17","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[]
[]
["Chart 33: Major Business and Industry developments - Number of decisions"]
["Year/ Quarter",null,"All Applications","Post-August 2009"]
["2012/13","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2013/14","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2014/15","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2015/16","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2016/17","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[]
[]
[]
[]
[]
["Chart 34: Major Business and Industry developments - Average decision time (weeks)"]
["Year/ Quarter",null,"All Applications","Post-August 2009"]
["2012/13","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2013/14","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2014/15","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2015/16","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2016/17","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[]
[]
[]
[]
[]
["Chart 35: Local developments with Legal Agreements -  Number of decisions "]
["Year/ Quarter",null,"All Applications","Post-August 2009"]
["2012/13","Q1",132,108]
[null,"Q2",98,95]
[null,"Q3",111,97]
[null,"Q4",125,115]
["2013/14","Q1",99,84]
[null,"Q2",116,104]
[null,"Q3",102,90]
[null,"Q4",115,105]
["2014/15","Q1",141,136]
[null,"Q2",112,103]
[null,"Q3",82,79]
[null,"Q4",125,115]
["2015/16","Q1",125,121]
[null,"Q2",101,97]
[null,"Q3",130,122]
[null,"Q4",113,111]
["2016/17","Q1",128,128]
[null,"Q2",138,137,null,"Aberdeenshire figures were amended"]
[null,"Q3",102,102]
[null,"Q4",131,131]
[]
["Chart 36: Local developments with Legal Agreements - Average decision time (weeks)"]
["Year/ Quarter",null,"All Applications","Post-August 2009"]
["2012/13","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2013/14","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2014/15","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2015/16","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2016/17","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[]
[]
[]
[]
[]
["Chart 37: Major developments with Legal Agreements -  Number of decisions "]
["Year/ Quarter",null,"All Applications","Post-August 2009"]
["2012/13","Q1",22,17]
[null,"Q2",23,10]
[null,"Q3",26,17]
[null,"Q4",21,14]
["2013/14","Q1",22,17]
[null,"Q2",22,14]
[null,"Q3",30,23]
[null,"Q4",37,32]
["2014/15","Q1",21,17]
[null,"Q2",16,12]
[null,"Q3",16,14]
[null,"Q4",17,14]
["2015/16","Q1",15,13]
[null,"Q2",21,17]
[null,"Q3",20,18]
[null,"Q4",24,19]
["2016/17","Q1",24,24]
[null,"Q2",18,18]
[null,"Q3",34,34]
[null,"Q4",25,24]
[]
[]
[]
[]
["Chart 38: Major developments with Legal Agreements - Average decision time (weeks) "]
["Year/ Quarter",null,"All Applications","Post-August 2009"]
["2012/13","Q1",98.987012987012989,55.974789915966383]
[null,"Q2",101.98136645962732,61.857142857142854]
[null,"Q3",105.9835164835165,57.210084033613441]
[null,"Q4",93.244897959183675,58.387755102040806]
["2013/14","Q1",103.82467532467533,71.588235294117652]
[null,"Q2",122.57142857142857,54.132653061224495]
[null,"Q3",67.666666666666671,49.385093167701868]
[null,"Q4",68.895752895752892,48.401785714285715]
["2014/15","Q1",79.639455782312922,45.378151260504204]
[null,"Q2",95.008928571428569,72.321428571428569]
[null,"Q3",91.964285714285722,75.520408163265301]
[null,"Q4",107.59663865546219,67.989795918367349]
["2015/16","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
["2016/17","Q1",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q2",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q3",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]
[null,"Q4",{"$f":"#REF!","v":{"$error":"#REF!"}},{"$f":"#REF!","v":{"$error":"#REF!"}}]

{"sheet":"SCOTLAND","index":8,"n_rows":80,"n_cols":13,"rows_kept":80,"cut":false,"hidden":false,"merged":[[75,0,78,3],[0,8,1,12]]}
["Planning Authority Performance Statistics1,2",null,null,"SCOTLAND",null,null,null,null,"For Scottish Government Use during analysis\nPlease do not delete or move these columns"]
[null,null,null,"2018/19 Q3"]
[null,null,null,"Post-3rd August 2009",null,null,null,null,null,"Check total number of applications"]
[null,null,null,null,null,null,null,null,null,null,{"$f":"SUM('Aberdeen City:West Lothian'!J3)","v":8700},"total apps",{"$f":"IF(ROUND(B6+B13+B17+B49+B50,6)=ROUND(K4,6),\"OK\",\"error - check summary and legacy\")","v":"error - check summary and legacy"}]
["Category","Total Number of Decisions","% Within Agreed Timescales",null,null,null,null,null,"Check PA Totals",null,{"$f":"ROUND(B6+B13+B17+B49+B50,6)","v":8696},"from summary","OK total is 8696+4 8700"]
["Processing Agreements",{"$f":"SUM(B7:B10)","v":683},0.79941434846266468,null,null,null,null,null,{"$f":"IF(SUM(B7:B10)=B6,\"ok\",\"error\")","v":"ok"},null,4,"legacy"]
["Major Applications",{"$f":"SUM('Aberdeen City:West Lothian'!B7)","v":28},0.7857142857142857]
["Local Applications",{"$f":"SUM('Aberdeen City:West Lothian'!B8)","v":546},0.80219780219780223]
["EIA developments",{"$f":"SUM('Aberdeen City:West Lothian'!B9)","v":0},"-"]
["Other Consents",{"$f":"SUM('Aberdeen City:West Lothian'!B10)","v":109},0.78899082568807344]
[]
[null,"Total Number of Decisions","Proportion of Decisions","Average Time (Weeks)",null,null,null,null,"Check Totals"]
["All Major Developments",{"$f":"SUM('Aberdeen City:West Lothian'!B13)","v":58},null,26.455665024630544,null,null,null,null,{"$f":"IF(B13=B14+B15,\"ok\",\"error\")","v":"ok"},{"$f":"IF(C14+C15=1,\"ok\",\"error\")","v":"ok"},{"$f":"C14*D14+C15*D15","v":26.455665024630541},{"$f":"IF(D13=K13,\"ok\",\"error\")","v":"ok"}]
["Without Legal Agreement",{"$f":"SUM('Aberdeen City:West Lothian'!B14)","v":40},{"$f":"B14/B13","v":0.68965517241379315},19.653571428571428]
["With Legal Agreement",{"$f":"SUM('Aberdeen City:West Lothian'!B15)","v":18},{"$f":"B15/B13","v":0.31034482758620691},41.571428571428569]
[]
["All Local Developments",{"$f":"SUM('Aberdeen City:West Lothian'!B17)","v":6155},null,8.8390391087385414,null,null,null,null,{"$f":"IF(B17=B18+B19,\"ok\",\"error\")","v":"ok"},{"$f":"IF(C18+C19=1,\"ok\",\"error\")","v":"ok"},{"$f":"C18*D18+C19*D19","v":8.8390391087385378},{"$f":"IF(ROUND(D17,2)=ROUND(K17,2),\"ok\",\"error\")","v":"ok"}]
["Without Legal Agreement",{"$f":"SUM('Aberdeen City:West Lothian'!B18)","v":6076},{"$f":"B18/B17","v":0.98716490658001621},8.4362127339415025]
["With Legal Agreement",{"$f":"SUM('Aberdeen City:West Lothian'!B19)","v":79},{"$f":"B19/B17","v":1.2835093419983753E-2},39.820976491862567]
["Local: less than 2 months",{"$f":"SUM('Aberdeen City:West Lothian'!B20)","v":4728},{"$f":"B20/B17","v":0.76815597075548336},6.432831762146483,null,null,null,null,{"$f":"IF(B17=B20+B21,\"ok\",\"error\")","v":"ok"},{"$f":"IF(C20+C21=1,\"ok\",\"error\")","v":"ok"},{"$f":"C20*D20+C21*D21","v":8.8390391087385431},{"$f":"IF(ROUND(D17,6)=ROUND(K20,6),\"ok\",\"error\")","v":"ok"}]
["Local: more than 2 months",{"$f":"SUM('Aberdeen City:West Lothian'!B21)","v":1427},{"$f":"B21/B17","v":0.23184402924451666},16.811392531784971]
[]
["All Local developments (non-householder)",{"$f":"SUM('Aberdeen City:West Lothian'!B23)","v":3111},null,10.680121228819397,null,null,null,null,{"$f":"IF(B23=B24+B25,\"ok\",\"error\")","v":"ok"},{"$f":"IF(C24+C25=1,\"ok\",\"error\")","v":"ok"},{"$f":"C24*D24+C25*D25","v":10.680121228819401},{"$f":"IF(D23=K23,\"ok\",\"error\")","v":"ok"}]
["Local: less than 2 months",{"$f":"SUM('Aberdeen City:West Lothian'!B24)","v":2046},{"$f":"B24/B23","v":0.65766634522661527},6.6627565982404695]
["Local: more than 2 months",{"$f":"SUM('Aberdeen City:West Lothian'!B25)","v":1065},{"$f":"B25/B23","v":0.34233365477338479},18.397987927565399]
[]
["Householder developments",{"$f":"SUM('Aberdeen City:West Lothian'!B27)","v":3044},null,6.9574338276703589,null,null,null,null,{"$f":"IF(B27=B28+B29,\"ok\",\"error\")","v":"ok"},{"$f":"IF(C28+C29=1,\"ok\",\"error\")","v":"ok"},{"$f":"C28*D28+C29*D29","v":6.9574338276703598},{"$f":"IF(ROUND(D27,6)=ROUND(K27,6),\"ok\",\"error\")","v":"ok"}]
["Local: less than 2 months",{"$f":"SUM('Aberdeen City:West Lothian'!B28)","v":2682},{"$f":"B28/B27","v":0.8810775295663601},6.2574304889741139]
["Local: more than 2 months",{"$f":"SUM('Aberdeen City:West Lothian'!B29)","v":362},{"$f":"B29/B27","v":0.11892247043363995},12.143646408839782]
[]
["Housing Developments - Major",{"$f":"SUM('Aberdeen City:West Lothian'!B31)","v":28},null,30.02551020408163]
[]
["Housing Developments - Local",{"$f":"SUM('Aberdeen City:West Lothian'!B33)","v":1169},null,12.251863619699376,null,null,null,null,{"$f":"IF(B33=B34+B35,\"ok\",\"error\")","v":"ok"},{"$f":"IF(C34+C35=1,\"ok\",\"error\")","v":"ok"},{"$f":"C34*D34+C35*D35","v":12.251863619699375},{"$f":"IF(D33=K33,\"ok\",\"error\")","v":"ok"}]
["Local: less than 2 months",{"$f":"SUM('Aberdeen City:West Lothian'!B34)","v":699},{"$f":"B34/B33","v":0.59794696321642427},6.7937870427140821]
["Local: more than 2 months",{"$f":"SUM('Aberdeen City:West Lothian'!B35)","v":470},{"$f":"B35/B33","v":0.40205303678357568},20.369300911854101]
[]
["Business & Industry - Major",{"$f":"SUM('Aberdeen City:West Lothian'!B37)","v":8},null,13.375000000000002]
[]
["Business & Industry - Local",{"$f":"SUM('Aberdeen City:West Lothian'!B39)","v":372},null,9.2139016897081429,null,null,null,null,{"$f":"IF(B39=B40+B41,\"ok\",\"error\")","v":"ok"},{"$f":"IF(C40+C41=1,\"ok\",\"error\")","v":"ok"},{"$f":"C40*D40+C41*D41","v":9.2139016897081429},{"$f":"IF(D39=K39,\"ok\",\"error\")","v":"ok"}]
["Local: less than 2 months",{"$f":"SUM('Aberdeen City:West Lothian'!B40)","v":261},{"$f":"B40/B39","v":0.70161290322580649},6.724137931034484]
["Local: more than 2 months",{"$f":"SUM('Aberdeen City:West Lothian'!B41)","v":111},{"$f":"B41/B39","v":0.29838709677419356},15.068211068211069]
[]
["Other developments - Major",{"$f":"SUM('Aberdeen City:West Lothian'!B43)","v":19},null,25.992481203007515]
[]
["Other developments - Local",{"$f":"SUM('Aberdeen City:West Lothian'!B45)","v":1408},null,9.660105519480517,null,null,null,null,{"$f":"IF(B45=B46+B47,\"ok\",\"error\")","v":"ok"},{"$f":"IF(C46+C47=1,\"ok\",\"error\")","v":"ok"},{"$f":"C46*D46+C47*D47","v":9.660105519480517},{"$f":"IF(ROUND(D45,6)=ROUND(K45,6),\"ok\",\"error\")","v":"ok"}]
["Local: less than 2 months",{"$f":"SUM('Aberdeen City:West Lothian'!B46)","v":978},{"$f":"B46/B45","v":0.69460227272727271},6.515775635407536]
["Local: more than 2 months",{"$f":"SUM('Aberdeen City:West Lothian'!B47)","v":430},{"$f":"B47/B45","v":0.30539772727272729},16.811627906976742]
[]
["EIA Developments",{"$f":"SUM('Aberdeen City:West Lothian'!B49)","v":3},null,21.904761904761902]
["Other Consents",{"$f":"SUM('Aberdeen City:West Lothian'!B50)","v":1797},null,7.5998887033945461]
[]
["Decision Making: Applications subject to"]
["Planning/Legal Agreements",{"$f":"SUM('Aberdeen City:West Lothian'!B53)","v":100},null,39.164285714285718,null,null,null,null,"Check Local Review Totals"]
["Local Reviews",{"$f":"SUM('Aberdeen City:West Lothian'!B54)","v":146},null,11.003913894324853,null,null,null,null,{"$f":"IF(B54=B59,\"ok\",\"error\")","v":"ok"}]
[]
["Decision Making: Local Reviews and Appeals"]
[]
[null,"Total number of decisions","Original decision upheld (%)"]
["Local Reviews",{"$f":"SUM('Aberdeen City:West Lothian'!B59)","v":146},0.55506849315068496]
["Appeals to Scottish Ministers3",{"$f":"SUM('Aberdeen City:West Lothian'!B60)","v":90},0.51126666666666665]
[]
["Enforcement Activity"]
[]
[null,"Number"]
["Cases Taken Up",1237]
["Notices Served",139]
["Reports to Procurator Fiscal",2]
["Prosecutions",0]
[]
["Approved and Delegated"]
[]
["Percentage Approved",{"$f":"J72/K72","v":0.93534640204553754},null,null,null,null,null,null,"Approved",{"$f":"SUM('Aberdeen City:West Lothian'!$J$72)","v":7682},{"$f":"SUM('Aberdeen City:West Lothian'!$K$72)","v":8213},"Total Applications less N17"]
["Percentage Delegated",{"$f":"J73/K73","v":0.96425287356321843},null,null,null,null,null,null,"Delegated",{"$f":"SUM('Aberdeen City:West Lothian'!$J$73)","v":8389},{"$f":"SUM('Aberdeen City:West Lothian'!K$73)","v":8700},"Total Applications"]
[null,null,null,null,null,null,null,null,null,null,{"$f":"SUM('Aberdeen City:West Lothian'!K74) - 'Cairngorms National Park'!K74","v":9459},"Applications received (excludes Cairngorms)"]
["1. For a full description of the categories in this analysis please see NOTES page.",null,null,null,null,null,null,null,"Check % approved",null,"OK"]
["2. Time has been removed from the decision time for a total of 478 applications where delays were outwith the control of 29 local authorities. Other local authorities either indicated that they were not able to provide details of dates for delays that were outwith their control or did not require any decision time to be removed from any of their applications. Average decision times for those local authorities who are not able to provide details for delays may be higher than otherwise, and higher than those authorities who are able to report delays in decision making. ",null,null,null,null,null,null,null,"Check % Delegated",null,"OK"]
[]
[null,null,null,null,null,null,null,null,null,null,null," "]
[]
["3. Cases where the decision was recalled and made by Ministers are not included in these figures."]

{"sheet":"Aberdeen City","index":9,"n_rows":77,"n_cols":13,"rows_kept":77,"cut":false,"hidden":false,"merged":[[61,0,61,3],[2,5,2,7],[76,0,77,3],[0,8,0,12]]}
["Planning Authority Performance Statistics1,3",null,null,"Aberdeen City",null,null,null,null,"For Scottish Government Use during analysis\nPlease do not delete or move these columns"]
[null,null,null,"2018/19 Q3",null,null,null,null,null,"Check total number of applications"]
[null,null,null,"All Applications excluding Legacy Cases",null,null,null,null,null,292,"total apps",null,"OK"]
[null,null,null,null,null,null,null,null,null," "]
["Processing Agreements","Total Number of Decisions","% Within Agreed Timescales"]
["TOTAL",104,1]
["Major Applications",3,1]
["Local Applications",75,1]
["EIA  Applications",0,"-"]
["Other Applications",26,1]
["Applications with processing agreements are not included in the following figures."]
[null,"Total Number of Decisions","Proportion of Decisions","Average Time (Weeks)",null,null,null,null,null,"check sums to total"]
["All Major Developments",2,null,25.928571428571427,null,null,null,null,null,"OK","OK",{"$error":"#VALUE!"}]
["Without Legal Agreement",0,0,"-"]
["With Legal Agreement",2,1,25.928571428571427]
[null,null,null,null,null,null,null,null,null,"OK"]
["All Local Developments",127,null,7.4364454443194603,null,null,null,null,null,"OK","OK","OK"]
["Without Legal Agreement",123,0.96850393700787396,6.6434378629500586]
["With Legal Agreement",4,3.1496062992125984E-2,31.821428571428573]
["Local: less than 2 months",121,0.952755905511811,6.5171192443919717,null,null,null,null,null,"OK","OK","OK"]
["Local: more than 2 months",6,4.7244094488188976E-2,25.976190476190478]
[]
["All Local developments (non-householder)",52,null,8.3983516483516478,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",46,0.88461538461538458,6.1055900621118013]
["Local: more than 2 months",6,0.11538461538461539,25.976190476190478]
[]
["Householder developments",75,null,6.7695238095238093,null,null,null,null,null,"OK","OK",{"$error":"#VALUE!"}]
["Local: less than 2 months",75,1,6.7695238095238093]
["Local: more than 2 months",0,0,"-"]
[]
["Housing Developments - Major",0,null,"-"]
[]
["Housing Developments - Local",7,null,21.653061224489797,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",3,0.42857142857142855,6.6666666666666661]
["Local: more than 2 months",4,0.5714285714285714,32.892857142857146]
[]
["Business & Industry - Major",0,null,"-"]
[]
["Business & Industry - Local",5,null,5.7142857142857144,null,null,null,null,null,"OK","OK",{"$error":"#VALUE!"}]
["Local: less than 2 months",5,1,5.7142857142857144]
["Local: more than 2 months",0,0,"-"]
[]
["Other developments - Major",2,null,25.928571428571427,null,null,null,null,null," "]
[]
["Other developments - Local",36,null,6.3492063492063489,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",34,0.94444444444444442,6.0084033613445387]
["Local: more than 2 months",2,5.5555555555555552E-2,12.142857142857142]
[]
["EIA Developments",0,null,"-"]
["Other Consents",59,null,5.9273607748184025]
[]
["Decision Making: Applications subject to"]
["Planning/Legal Agreements",6,null,29.857142857142858]
["Local Reviews",13,null,7.615384615384615,null,null,null,null,null,"Check local review totals"]
[null,null,null,null,null,null,null,null,null,"OK"]
["Decision Making: Local Reviews and Appeals"]
[]
[null,"Total number of decisions","Original decision upheld (%)"]
["Local Reviews",13,0.23076923076923078]
["Appeals to Scottish Ministers2",3,0.33300000000000002]
[]
["Enforcement Activity"]
[]
[null,"Number"]
["Cases Taken Up",30]
["Notices Served",2]
["Reports to Procurator Fiscal",0]
["Prosecutions",0]
["Number of breaches resolved",21]
["Approved and Delegated"]
[]
["Percentage Approved",0.90714285714285714,null,null,null,null,null,null,"Approved",254,280,"Total Applications less N17"]
["Percentage Delegated",0.96575342465753422,null,null,null,null,null,null,"Delegated",282,292,"Total Applications"]
[null,null,null,null,null,null,null,null,null,null,331,"applications received"]
["1. For a full description of the categories in this analysis please see NOTES page."]
["2. Cases where the decision was recalled and made by Ministers are not included in these figures."]
["3. Time has been removed from the decision time for 8 applications where delays were outwith the control of the local authority."]

{"sheet":"Aberdeenshire","index":10,"n_rows":77,"n_cols":13,"rows_kept":77,"cut":false,"hidden":false,"merged":[[61,0,61,3],[2,5,2,7],[0,8,0,12],[76,0,77,3]]}
["Planning Authority Performance Statistics1,3",null,null,"Aberdeenshire ",null,null,null,null,"For Scottish Government Use during analysis\nPlease do not delete or move these columns"]
[null,null,null,"2018/19 Q3",null,null,null,null,null,"Check total number of applications"]
[null,null,null,"All Applications excluding Legacy Cases",null,null,null,null,null,609,"total apps",null,"OK"]
[null,null,null,null,null,null,null,null,null," "]
["Processing Agreements","Total Number of Decisions","% Within Agreed Timescales"]
["TOTAL",120,0.9]
["Major Applications",2,1]
["Local Applications",105,0.89523809523809528]
["EIA  Applications",0,"-"]
["Other Applications",13,0.92307692307692313]
["Applications with processing agreements are not included in the following figures."]
[null,"Total Number of Decisions","Proportion of Decisions","Average Time (Weeks)",null,null,null,null,null,"check sums to total"]
["All Major Developments",1,null,16.714285714285715,null,null,null,null,null,"OK","OK",{"$error":"#VALUE!"}]
["Without Legal Agreement",1,1,16.714285714285715]
["With Legal Agreement",0,0,"-"]
[null,null,null,null,null,null,null,null,null,"OK"]
["All Local Developments",425,null,7.7778151260504202,null,null,null,null,null,"OK","OK","OK"]
["Without Legal Agreement",410,0.96470588235294119,7.6993031358885018]
["With Legal Agreement",15,3.5294117647058823E-2,9.9238095238095241]
["Local: less than 2 months",379,0.8917647058823529,7.0569166980776483,null,null,null,null,null,"OK","OK","OK"]
["Local: more than 2 months",46,0.10823529411764705,13.717391304347826]
[]
["All Local developments (non-householder)",253,null,8.233201581027668,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",220,0.86956521739130432,7.3798701298701292]
["Local: more than 2 months",33,0.13043478260869565,13.922077922077921]
[]
["Householder developments",172,null,7.1079734219269097,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",159,0.92441860465116277,6.6100628930817606]
["Local: more than 2 months",13,7.5581395348837205E-2,13.197802197802199]
[]
["Housing Developments - Major",0,null,"-"]
[]
["Housing Developments - Local",118,null,8.4491525423728806,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",102,0.86440677966101698,7.598039215686275]
["Local: more than 2 months",16,0.13559322033898305,13.875]
[]
["Business & Industry - Major",1,null,16.714285714285715]
[]
["Business & Industry - Local",33,null,7.7489177489177488,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",28,0.84848484848484851,7.0459183673469381]
["Local: more than 2 months",5,0.15151515151515152,11.685714285714285]
[]
["Other developments - Major",0,null,"-",null,null,null,null,null," "]
[]
["Other developments - Local",77,null,7.8181818181818183,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",69,0.89610389610389607,7.1718426501035202]
["Local: more than 2 months",8,0.1038961038961039,13.392857142857142]
[]
["EIA Developments",0,null,"-"]
["Other Consents",63,null,7.4852607709750574]
[]
["Decision Making: Applications subject to"]
["Planning/Legal Agreements",15,null,9.9238095238095241]
["Local Reviews",7,null,10.795918367346939,null,null,null,null,null,"Check local review totals"]
[null,null,null,null,null,null,null,null,null,"OK"]
["Decision Making: Local Reviews and Appeals"]
[]
[null,"Total number of decisions","Original decision upheld (%)"]
["Local Reviews",7,1]
["Appeals to Scottish Ministers2",7,0.57099999999999995]
[]
["Enforcement Activity"]
[]
[null,"Number"]
["Cases Taken Up",92]
["Notices Served",0]
["Reports to Procurator Fiscal",0]
["Prosecutions",0]
["Number of breaches resolved",94]
["Approved and Delegated"]
[]
["Percentage Approved",0.92821368948247074,null,null,null,null,null,null,"Approved",556,599,"Total Applications less N17"]
["Percentage Delegated",0.92610837438423643,null,null,null,null,null,null,"Delegated",564,609,"Total Applications"]
[null,null,null,null,null,null,null,null,null,null,629,"applications received"]
["1. For a full description of the categories in this analysis please see NOTES page."]
["2. Cases where the decision was recalled and made by Ministers are not included in these figures."]
["3. Time has been removed from the decision time for 4 applications where delays were outwith the control of the local authority."]

{"sheet":"Angus","index":11,"n_rows":77,"n_cols":13,"rows_kept":77,"cut":false,"hidden":false,"merged":[[61,0,61,3],[2,5,2,7],[0,8,0,12]]}
["Planning Authority Performance Statistics1,3",null,null,"Angus",null,null,null,null,"For Scottish Government Use during analysis\nPlease do not delete or move these columns"]
[null,null,null,"2018/19 Q3",null,null,null,null,null,"Check total number of applications"]
[null,null,null,"All Applications excluding Legacy Cases",null,null,null,null,null,189,"total apps",null,"OK"]
[null,null,null,null,null,null,null,null,null," "]
["Processing Agreements","Total Number of Decisions","% Within Agreed Timescales"]
["TOTAL",35,0.94285714285714284]
["Major Applications",0,"-"]
["Local Applications",31,0.967741935483871]
["EIA  Applications",0,"-"]
["Other Applications",4,0.75]
["Applications with processing agreements are not included in the following figures."]
[null,"Total Number of Decisions","Proportion of Decisions","Average Time (Weeks)",null,null,null,null,null,"check sums to total"]
["All Major Developments",1,null,10.285714285714286,null,null,null,null,null,"OK","OK",{"$error":"#VALUE!"}]
["Without Legal Agreement",1,1,10.285714285714286]
["With Legal Agreement",0,0,"-"]
[null,null,null,null,null,null,null,null,null,"OK"]
["All Local Developments",128,null,6.5859375,null,null,null,null,null,"OK","OK",{"$error":"#VALUE!"}]
["Without Legal Agreement",128,1,6.5859375]
["With Legal Agreement",0,0,"-"]
["Local: less than 2 months",117,0.9140625,6.1941391941391943,null,null,null,null,null,"OK","OK","OK"]
["Local: more than 2 months",11,8.59375E-2,10.753246753246753]
[]
["All Local developments (non-householder)",61,null,7.5105386416861828,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",52,0.85245901639344257,6.9587912087912089]
["Local: more than 2 months",9,0.14754098360655737,10.698412698412698]
[]
["Householder developments",67,null,5.7441364605543708,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",65,0.97014925373134331,5.582417582417583]
["Local: more than 2 months",2,2.9850746268656716E-2,11]
[]
["Housing Developments - Major",1,null,10.285714285714286]
[]
["Housing Developments - Local",23,null,7.3105590062111796,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",19,0.82608695652173914,6.8646616541353387]
["Local: more than 2 months",4,0.17391304347826086,9.4285714285714288]
[]
["Business & Industry - Major",0,null,"-"]
[]
["Business & Industry - Local",11,null,7.7272727272727275,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",9,0.81818181818181823,7.4444444444444446]
["Local: more than 2 months",2,0.18181818181818182,9]
[]
["Other developments - Major",0,null,"-",null,null,null,null,null," "]
[]
["Other developments - Local",27,null,7.5925925925925926,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",24,0.88888888888888884,6.8511904761904763]
["Local: more than 2 months",3,0.1111111111111111,13.523809523809524]
[]
["EIA Developments",0,null,"-"]
["Other Consents",25,null,6]
[]
["Decision Making: Applications subject to"]
["Planning/Legal Agreements",0,null,"-"]
["Local Reviews",2,null,10.785714285714286,null,null,null,null,null,"Check local review totals"]
[null,null,null,null,null,null,null,null,null,"OK"]
["Decision Making: Local Reviews and Appeals"]
[]
[null,"Total number of decisions","Original decision upheld (%)"]
["Local Reviews",2,1]
["Appeals to Scottish Ministers2",0]
[]
["Enforcement Activity"]
[]
[null,"Number"]
["Cases Taken Up",15]
["Notices Served",6]
["Reports to Procurator Fiscal",0]
["Prosecutions",0]
["Number of breaches resolved",4]
["Approved and Delegated"]
[]
["Percentage Approved",0.98360655737704916,null,null,null,null,null,null,"Approved",180,183,"Total Applications less N17"]
["Percentage Delegated",0.95238095238095233,null,null,null,null,null,null,"Delegated",180,189,"Total Applications"]
[null,null,null,null,null,null,null,null,null,null,186,"applications received"]
["1. For a full description of the categories in this analysis please see NOTES page."]
["2. Cases where the decision was recalled and made by Ministers are not included in these figures."]
["3. Time has not been removed from the decision time for any applications."]

{"sheet":"Argyll and Bute","index":12,"n_rows":77,"n_cols":13,"rows_kept":77,"cut":false,"hidden":false,"merged":[[76,0,77,3],[2,5,2,7],[0,8,0,12],[61,0,61,3]]}
["Planning Authority Performance Statistics1,3",null,null,"Argyll and Bute",null,null,null,null,"For Scottish Government Use during analysis\nPlease do not delete or move these columns"]
[null,null,null,"2018/19 Q3",null,null,null,null,null,"Check total number of applications"]
[null,null,null,"All Applications excluding Legacy Cases",null,null,null,null,null,329,"total apps",null,"OK"]
[null,null,null,null,null,null,null,null,null," "]
["Processing Agreements","Total Number of Decisions","% Within Agreed Timescales"]
["TOTAL",0,"-"]
["Major Applications",0,"-"]
["Local Applications",0,"-"]
["EIA  Applications",0,"-"]
["Other Applications",0,"-"]
["Applications with processing agreements are not included in the following figures."]
[null,"Total Number of Decisions","Proportion of Decisions","Average Time (Weeks)",null,null,null,null,null,"check sums to total"]
["All Major Developments",2,null,9.7857142857142865,null,null,null,null,null,"OK","OK",{"$error":"#VALUE!"}]
["Without Legal Agreement",2,1,9.7857142857142865]
["With Legal Agreement",0,0,"-"]
[null,null,null,null,null,null,null,null,null,"OK"]
["All Local Developments",265,null,8.8188679245283019,null,null,null,null,null,"OK","OK",{"$error":"#VALUE!"}]
["Without Legal Agreement",265,1,8.8188679245283019]
["With Legal Agreement",0,0,"-"]
["Local: less than 2 months",186,0.70188679245283014,6.2818740399385566,null,null,null,null,null,"OK","OK","OK"]
["Local: more than 2 months",79,0.2981132075471698,14.792043399638336]
[]
["All Local developments (non-householder)",175,null,9.6644897959183673,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",114,0.65142857142857147,6.7167919799498748]
["Local: more than 2 months",61,0.34857142857142859,15.173302107728336]
[]
["Householder developments",90,null,7.1746031746031749,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",72,0.8,5.5932539682539684]
["Local: more than 2 months",18,0.2,13.5]
[]
["Housing Developments - Major",1,null,12.285714285714286]
[]
["Housing Developments - Local",92,null,9.933229813664596,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",57,0.61956521739130432,6.8847117794486214]
["Local: more than 2 months",35,0.38043478260869568,14.897959183673469]
[]
["Business & Industry - Major",1,null,7.2857142857142856]
[]
["Business & Industry - Local",3,null,7.2857142857142856,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",2,0.66666666666666663,6.2142857142857144]
["Local: more than 2 months",1,0.33333333333333331,9.4285714285714288]
[]
["Other developments - Major",0,null,"-",null,null,null,null,null," "]
[]
["Other developments - Local",67,null,9.9275053304904048,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",43,0.64179104477611937,6.5913621262458468]
["Local: more than 2 months",24,0.35820895522388058,15.904761904761903]
[]
["EIA Developments",0,null,"-"]
["Other Consents",62,null,6.7949308755760365]
[]
["Decision Making: Applications subject to"]
["Planning/Legal Agreements",0,null,"-"]
["Local Reviews",1,null,6.1428571428571432,null,null,null,null,null,"Check local review totals"]
[null,null,null,null,null,null,null,null,null,"OK"]
["Decision Making: Local Reviews and Appeals"]
[]
[null,"Total number of decisions","Original decision upheld (%)"]
["Local Reviews",1,1]
["Appeals to Scottish Ministers2",1,1]
[]
["Enforcement Activity"]
[]
[null,"Number"]
["Cases Taken Up",108]
["Notices Served",24]
["Reports to Procurator Fiscal",0]
["Prosecutions",0]
["Number of breaches resolved",93]
["Approved and Delegated"]
[]
["Percentage Approved",0.96784565916398713,null,null,null,null,null,null,"Approved",301,311,"Total Applications less N17"]
["Percentage Delegated",0.99088145896656532,null,null,null,null,null,null,"Delegated",326,329,"Total Applications"]
[null,null,null,null,null,null,null,null,null,null,355,"applications received"]
["1. For a full description of the categories in this analysis please see NOTES page."]
["2. Cases where the decision was recalled and made by Ministers are not included in these figures."]
["3. Time has been removed from the decision time for 16 applications where delays were outwith the control of the local authority."]

{"sheet":"Cairngorms National Park","index":13,"n_rows":77,"n_cols":13,"rows_kept":77,"cut":false,"hidden":false,"merged":[[61,0,61,3],[2,5,2,7],[0,8,0,12]]}
["Planning Authority Performance Statistics1,3",null,null,"Cairngorms National Park",null,null,null,null,"For Scottish Government Use during analysis\nPlease do not delete or move these columns"]
[null,null,null,"2018/19 Q3",null,null,null,null,null,"Check total number of applications"]
[null,null,null,"All Applications excluding Legacy Cases",null,null,null,null,null,10,"total apps",null,"OK"]
[null,null,null,null,null,null,null,null,null," "]
["Processing Agreements","Total Number of Decisions","% Within Agreed Timescales"]
["TOTAL",9,0.66666666666666663]
["Major Applications",0,"-"]
["Local Applications",9,0.66666666666666663]
["EIA  Applications",0,"-"]
["Other Applications",0,"-"]
["Applications with processing agreements are not included in the following figures."]
[null,"Total Number of Decisions","Proportion of Decisions","Average Time (Weeks)",null,null,null,null,null,"check sums to total"]
["All Major Developments",0,null,"-",null,null,null,null,null,"OK",{"$error":"#VALUE!"},{"$error":"#VALUE!"}]
["Without Legal Agreement",0,"-","-"]
["With Legal Agreement",0,"-","-"]
[null,null,null,null,null,null,null,null,null,"OK"]
["All Local Developments",1,null,8,null,null,null,null,null,"OK","OK",{"$error":"#VALUE!"}]
["Without Legal Agreement",1,1,8]
["With Legal Agreement",0,0,"-"]
["Local: less than 2 months",1,1,8,null,null,null,null,null,"OK","OK",{"$error":"#VALUE!"}]
["Local: more than 2 months",0,0,"-"]
[]
["All Local developments (non-householder)",1,null,8,null,null,null,null,null,"OK","OK",{"$error":"#VALUE!"}]
["Local: less than 2 months",1,1,8]
["Local: more than 2 months",0,0,"-"]
[]
["Householder developments",0,null,"-",null,null,null,null,null,"OK",{"$error":"#VALUE!"},{"$error":"#VALUE!"}]
["Local: less than 2 months",0,"-","-"]
["Local: more than 2 months",0,"-","-"]
[]
["Housing Developments - Major",0,null,"-"]
[]
["Housing Developments - Local",0,null,"-",null,null,null,null,null,"OK",{"$error":"#VALUE!"},{"$error":"#VALUE!"}]
["Local: less than 2 months",0,"-","-"]
["Local: more than 2 months",0,"-","-"]
[]
["Business & Industry - Major",0,null,"-"]
[]
["Business & Industry - Local",0,null,"-",null,null,null,null,null,"OK",{"$error":"#VALUE!"},{"$error":"#VALUE!"}]
["Local: less than 2 months",0,"-","-"]
["Local: more than 2 months",0,"-","-"]
[]
["Other developments - Major",0,null,"-",null,null,null,null,null," "]
[]
["Other developments - Local",1,null,8,null,null,null,null,null,"OK","OK",{"$error":"#VALUE!"}]
["Local: less than 2 months",1,1,8]
["Local: more than 2 months",0,0,"-"]
[]
["EIA Developments",0,null,"-"]
["Other Consents",0,null,"-"]
[]
["Decision Making: Applications subject to"]
["Planning/Legal Agreements",0,null,"-"]
["Local Reviews",0,null,"-",null,null,null,null,null,"Check local review totals"]
[null,null,null,null,null,null,null,null,null,"OK"]
["Decision Making: Local Reviews and Appeals"]
[]
[null,"Total number of decisions","Original decision upheld (%)"]
["Local Reviews",0,"-"]
["Appeals to Scottish Ministers2",2,0]
[]
["Enforcement Activity"]
[]
[null,"Number"]
["Cases Taken Up",6]
["Notices Served",0]
["Reports to Procurator Fiscal",0]
["Prosecutions",0]
["Number of breaches resolved",15]
["Approved and Delegated"]
[]
["Percentage Approved",0.9,null,null,null,null,null,null,"Approved",9,10,"Total Applications less N17"]
["Percentage Delegated",0,null,null,null,null,null,null,"Delegated",0,10,"Total Applications"]
[null,null,null,null,null,null,null,null,null,null,4,"applications received"]
["1. For a full description of the categories in this analysis please see NOTES page."]
["2. Cases where the decision was recalled and made by Ministers are not included in these figures."]
["3. Time has not been removed from the decision time for any applications."]

{"sheet":"Clackmannanshire","index":14,"n_rows":77,"n_cols":13,"rows_kept":77,"cut":false,"hidden":false,"merged":[[79,0,80,3],[61,0,61,3],[76,0,77,3],[2,5,2,7],[0,8,0,12]]}
["Planning Authority Performance Statistics1,3",null,null,"Clackmannanshire",null,null,null,null,"For Scottish Government Use during analysis\nPlease do not delete or move these columns"]
[null,null,null,"2018/19 Q3",null,null,null,null,null,"Check total number of applications"]
[null,null,null,"All Applications excluding Legacy Cases",null,null,null,null,null,63,"total apps",null,"OK"]
[null,null,null,null,null,null,null,null,null," "]
["Processing Agreements","Total Number of Decisions","% Within Agreed Timescales"]
["TOTAL",0,"-"]
["Major Applications",0,"-"]
["Local Applications",0,"-"]
["EIA  Applications",0,"-"]
["Other Applications",0,"-"]
["Applications with processing agreements are not included in the following figures."]
[null,"Total Number of Decisions","Proportion of Decisions","Average Time (Weeks)",null,null,null,null,null,"check sums to total"]
["All Major Developments",0,null,"-",null,null,null,null,null,"OK",{"$error":"#VALUE!"},{"$error":"#VALUE!"}]
["Without Legal Agreement",0,"-","-"]
["With Legal Agreement",0,"-","-"]
[null,null,null,null,null,null,null,null,null,"OK"]
["All Local Developments",53,null,5.9703504043126685,null,null,null,null,null,"OK","OK",{"$error":"#VALUE!"}]
["Without Legal Agreement",53,1,5.9703504043126685]
["With Legal Agreement",0,0,"-"]
["Local: less than 2 months",51,0.96226415094339623,5.1064425770308119,null,null,null,null,null,"OK","OK","OK"]
["Local: more than 2 months",2,3.7735849056603772E-2,28]
[]
["All Local developments (non-householder)",17,null,8.7815126050420158,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",15,0.88235294117647056,6.2190476190476192]
["Local: more than 2 months",2,0.11764705882352941,28]
[]
["Householder developments",36,null,4.6428571428571432,null,null,null,null,null,"OK","OK",{"$error":"#VALUE!"}]
["Local: less than 2 months",36,1,4.6428571428571432]
["Local: more than 2 months",0,0,"-"]
[]
["Housing Developments - Major",0,null,"-"]
[]
["Housing Developments - Local",6,null,13.642857142857142,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",4,0.66666666666666663,6.4642857142857144]
["Local: more than 2 months",2,0.33333333333333331,28]
[]
["Business & Industry - Major",0,null,"-"]
[]
["Business & Industry - Local",6,null,5.8809523809523805,null,null,null,null,null,"OK","OK",{"$error":"#VALUE!"}]
["Local: less than 2 months",6,1,5.8809523809523805]
["Local: more than 2 months",0,0,"-"]
[]
["Other developments - Major",0,null,"-",null,null,null,null,null," "]
[]
["Other developments - Local",4,null,5.9285714285714288,null,null,null,null,null,"OK","OK",{"$error":"#VALUE!"}]
["Local: less than 2 months",4,1,5.9285714285714288]
["Local: more than 2 months",0,0,"-"]
[]
["EIA Developments",0,null,"-"]
["Other Consents",10,null,4.4285714285714288]
[]
["Decision Making: Applications subject to"]
["Planning/Legal Agreements",0,null,"-"]
["Local Reviews",0,null,"-",null,null,null,null,null,"Check local review totals"]
[null,null,null,null,null,null,null,null,null,"OK"]
["Decision Making: Local Reviews and Appeals"]
[]
[null,"Total number of decisions","Original decision upheld (%)"]
["Local Reviews",0,"-"]
["Appeals to Scottish Ministers2",0]
[]
["Enforcement Activity"]
[]
[null,"Number"]
["Cases Taken Up",8]
["Notices Served",0]
["Reports to Procurator Fiscal",0]
["Prosecutions",0]
["Number of breaches resolved",6]
["Approved and Delegated"]
[]
["Percentage Approved",0.9838709677419355,null,null,null,null,null,null,"Approved",61,62,"Total Applications less N17"]
["Percentage Delegated",0.98412698412698407,null,null,null,null,null,null,"Delegated",62,63,"Total Applications"]
[null,null,null,null,null,null,null,null,null,null,71,"applications received"]
["1. For a full description of the categories in this analysis please see NOTES page."]
["2. Cases where the decision was recalled and made by Ministers are not included in these figures."]
["3. Time has been removed from the decision time for 1 application where delays were outwith the control of the local authority."]

{"sheet":"Dumfries and Galloway","index":15,"n_rows":77,"n_cols":13,"rows_kept":77,"cut":false,"hidden":false,"merged":[[61,0,61,3],[76,0,77,3],[2,5,2,7],[0,8,0,12]]}
["Planning Authority Performance Statistics1,3",null,null,"Dumfries and Galloway ",null,null,null,null,"For Scottish Government Use during analysis\nPlease do not delete or move these columns"]
[null,null,null,"2018/19 Q3",null,null,null,null,null,"Check total number of applications"]
[null,null,null,"All Applications excluding Legacy Cases",null,null,null,null,null,313,"total apps",null,"OK"]
[null,null,null,null,null,null,null,null,null," "]
["Processing Agreements","Total Number of Decisions","% Within Agreed Timescales"]
["TOTAL",17,1]
["Major Applications",4,1]
["Local Applications",13,1]
["EIA  Applications",0,"-"]
["Other Applications",0,"-"]
["Applications with processing agreements are not included in the following figures."]
[null,"Total Number of Decisions","Proportion of Decisions","Average Time (Weeks)",null,null,null,null,null,"check sums to total"]
["All Major Developments",1,null,37.142857142857146,null,null,null,null,null,"OK","OK",{"$error":"#VALUE!"}]
["Without Legal Agreement",1,1,37.142857142857146]
["With Legal Agreement",0,0,"-"]
[null,null,null,null,null,null,null,null,null,"OK"]
["All Local Developments",237,null,8.3309222423146476,null,null,null,null,null,"OK","OK","OK"]
["Without Legal Agreement",236,0.99578059071729963,8.3395883777239721]
["With Legal Agreement",1,4.2194092827004216E-3,6.2857142857142856]
["Local: less than 2 months",169,0.71308016877637126,5.7836010143702454,null,null,null,null,null,"OK","OK","OK"]
["Local: more than 2 months",68,0.28691983122362869,14.661764705882351]
[]
["All Local developments (non-householder)",149,null,9.7085330776605936,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",87,0.58389261744966447,6.2151067323481115]
["Local: more than 2 months",62,0.41610738255033558,14.610599078341014]
[]
["Householder developments",88,null,5.9983766233766236,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",82,0.93181818181818177,5.3257839721254356]
["Local: more than 2 months",6,6.8181818181818177E-2,15.19047619047619]
[]
["Housing Developments - Major",1,null,37.142857142857146]
[]
["Housing Developments - Local",61,null,10.943793911007026,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",30,0.49180327868852458,6.8619047619047615]
["Local: more than 2 months",31,0.50819672131147542,14.894009216589863]
[]
["Business & Industry - Major",0,null,"-"]
[]
["Business & Industry - Local",0,null,"-",null,null,null,null,null,"OK",{"$error":"#VALUE!"},{"$error":"#VALUE!"}]
["Local: less than 2 months",0,"-","-"]
["Local: more than 2 months",0,"-","-"]
[]
["Other developments - Major",0,null,"-",null,null,null,null,null," "]
[]
["Other developments - Local",85,null,8.6907563025210077,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",56,0.6588235294117647,5.8647959183673475]
["Local: more than 2 months",29,0.3411764705882353,14.147783251231527]
[]
["EIA Developments",0,null,"-"]
["Other Consents",58,null,7.0221674876847286]
[]
["Decision Making: Applications subject to"]
["Planning/Legal Agreements",1,null,6.2857142857142856]
["Local Reviews",1,null,22.285714285714285,null,null,null,null,null,"Check local review totals"]
[null,null,null,null,null,null,null,null,null,"OK"]
["Decision Making: Local Reviews and Appeals"]
[]
[null,"Total number of decisions","Original decision upheld (%)"]
["Local Reviews",1,0]
["Appeals to Scottish Ministers2",4,0.5]
[]
["Enforcement Activity"]
[]
[null,"Number"]
["Cases Taken Up",31]
["Notices Served",1]
["Reports to Procurator Fiscal",0]
["Prosecutions",0]
["Number of breaches resolved",23]
["Approved and Delegated"]
[]
["Percentage Approved",0.93979933110367897,null,null,null,null,null,null,"Approved",281,299,"Total Applications less N17"]
["Percentage Delegated",0.92971246006389774,null,null,null,null,null,null,"Delegated",291,313,"Total Applications"]
[null,null,null,null,null,null,null,null,null,null,313,"applications received"]
["1. For a full description of the categories in this analysis please see NOTES page."]
["2. Cases where the decision was recalled and made by Ministers are not included in these figures."]
["3. Time has been removed from the decision time for 15 applications where delays were outwith the control of the local authority."]

{"sheet":"Dundee","index":16,"n_rows":77,"n_cols":13,"rows_kept":77,"cut":false,"hidden":false,"merged":[[61,0,61,3],[76,0,77,3],[2,5,2,7],[0,8,0,12]]}
["Planning Authority Performance Statistics1,3",null,null,"Dundee City",null,null,null,null,"For Scottish Government Use during analysis\nPlease do not delete or move these columns"]
[null,null,null,"2018/19 Q3",null,null,null,null,null,"Check total number of applications"]
[null,null,null,"All Applications excluding Legacy Cases",null,null,null,null,null,178,"total apps",null,"OK"]
[null,null,null,null,null,null,null,null,null," "]
["Processing Agreements","Total Number of Decisions","% Within Agreed Timescales"]
["TOTAL",0,"-"]
["Major Applications",0,"-"]
["Local Applications",0,"-"]
["EIA  Applications",0,"-"]
["Other Applications",0,"-"]
["Applications with processing agreements are not included in the following figures."]
[null,"Total Number of Decisions","Proportion of Decisions","Average Time (Weeks)",null,null,null,null,null,"check sums to total"]
["All Major Developments",2,null,17.285714285714285,null,null,null,null,null,"OK","OK",{"$error":"#VALUE!"}]
["Without Legal Agreement",2,1,17.285714285714285]
["With Legal Agreement",0,0,"-"]
[null,null,null,null,null,null,null,null,null,"OK"]
["All Local Developments",133,null,10.008592910848551,null,null,null,null,null,"OK","OK","OK"]
["Without Legal Agreement",132,0.99248120300751874,9.8961038961038952]
["With Legal Agreement",1,7.5187969924812026E-3,24.857142857142858]
["Local: less than 2 months",91,0.68421052631578949,7.4222919937205649,null,null,null,null,null,"OK","OK","OK"]
["Local: more than 2 months",42,0.31578947368421051,15.612244897959185]
[]
["All Local developments (non-householder)",62,null,11.988479262672811,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",36,0.58064516129032262,7.3373015873015879]
["Local: more than 2 months",26,0.41935483870967744,18.428571428571427]
[]
["Householder developments",71,null,8.2796780684104636,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",55,0.77464788732394363,7.4779220779220781]
["Local: more than 2 months",16,0.22535211267605634,11.035714285714286]
[]
["Housing Developments - Major",2,null,17.285714285714285]
[]
["Housing Developments - Local",12,null,12.571428571428571,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",3,0.25,6.9523809523809517]
["Local: more than 2 months",9,0.75,14.444444444444445]
[]
["Business & Industry - Major",0,null,"-"]
[]
["Business & Industry - Local",12,null,7.3452380952380949,null,null,null,null,null,"OK","OK",{"$error":"#VALUE!"}]
["Local: less than 2 months",12,1,7.3452380952380949]
["Local: more than 2 months",0,0,"-"]
[]
["Other developments - Major",0,null,"-",null,null,null,null,null," "]
[]
["Other developments - Local",36,null,13.583333333333332,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",19,0.52777777777777779,7.3609022556390977]
["Local: more than 2 months",17,0.47222222222222221,20.537815126050418]
[]
["EIA Developments",0,null,"-"]
["Other Consents",43,null,10.561461794019934]
[]
["Decision Making: Applications subject to"]
["Planning/Legal Agreements",1,null,24.857142857142858]
["Local Reviews",2,null,4.5,null,null,null,null,null,"Check local review totals"]
[null,null,null,null,null,null,null,null,null,"OK"]
["Decision Making: Local Reviews and Appeals"]
[]
[null,"Total number of decisions","Original decision upheld (%)"]
["Local Reviews",2,1]
["Appeals to Scottish Ministers2",0]
[]
["Enforcement Activity"]
[]
[null,"Number"]
["Cases Taken Up",15]
["Notices Served",0]
["Reports to Procurator Fiscal",0]
["Prosecutions",0]
["Number of breaches resolved",12]
["Approved and Delegated"]
[]
["Percentage Approved",0.94767441860465118,null,null,null,null,null,null,"Approved",163,172,"Total Applications less N17"]
["Percentage Delegated",0.949438202247191,null,null,null,null,null,null,"Delegated",169,178,"Total Applications"]
[null,null,null,null,null,null,null,null,null,null,145,"applications received"]
["1. For a full description of the categories in this analysis please see NOTES page."]
["2. Cases where the decision was recalled and made by Ministers are not included in these figures."]
["3. Time has been removed from the decision time for 7 applications where delays were outwith the control of the local authority."]

{"sheet":"East Ayrshire","index":17,"n_rows":77,"n_cols":13,"rows_kept":77,"cut":false,"hidden":false,"merged":[[61,0,61,3],[76,0,77,3],[2,5,2,7],[0,8,0,12]]}
["Planning Authority Performance Statistics1,3",null,null,"East Ayrshire",null,null,null,null,"For Scottish Government Use during analysis\nPlease do not delete or move these columns"]
[null,null,null,"2018/19 Q3",null,null,null,null,null,"Check total number of applications"]
[null,null,null,"All Applications excluding Legacy Cases",null,null,null,null,null,138,"total apps",null,"OK"]
[null,null,null,null,null,null,null,null,null," "]
["Processing Agreements","Total Number of Decisions","% Within Agreed Timescales"]
["TOTAL",13,7.6923076923076927E-2]
["Major Applications",0,"-"]
["Local Applications",12,8.3333333333333329E-2]
["EIA  Applications",0,"-"]
["Other Applications",1,0]
["Applications with processing agreements are not included in the following figures."]
[null,"Total Number of Decisions","Proportion of Decisions","Average Time (Weeks)",null,null,null,null,null,"check sums to total"]
["All Major Developments",0,null,"-",null,null,null,null,null,"OK",{"$error":"#VALUE!"},{"$error":"#VALUE!"}]
["Without Legal Agreement",0,"-","-"]
["With Legal Agreement",0,"-","-"]
[null,null,null,null,null,null,null,null,null,"OK"]
["All Local Developments",90,null,9.087301587301587,null,null,null,null,null,"OK","OK",{"$error":"#VALUE!"}]
["Without Legal Agreement",90,1,9.087301587301587]
["With Legal Agreement",0,0,"-"]
["Local: less than 2 months",76,0.84444444444444444,6.9981203007518795,null,null,null,null,null,"OK","OK","OK"]
["Local: more than 2 months",14,0.15555555555555556,20.428571428571427]
[]
["All Local developments (non-householder)",55,null,10.597402597402597,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",42,0.76363636363636367,7.3163265306122449]
["Local: more than 2 months",13,0.23636363636363636,21.197802197802197]
[]
["Householder developments",35,null,6.7142857142857144,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",34,0.97142857142857142,6.6050420168067223]
["Local: more than 2 months",1,2.8571428571428571E-2,10.428571428571429]
[]
["Housing Developments - Major",0,null,"-"]
[]
["Housing Developments - Local",18,null,13.253968253968253,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",11,0.61111111111111116,7.1558441558441563]
["Local: more than 2 months",7,0.3888888888888889,22.836734693877553]
[]
["Business & Industry - Major",0,null,"-"]
[]
["Business & Industry - Local",22,null,10.33116883116883,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",17,0.77272727272727271,7.2016806722689077]
["Local: more than 2 months",5,0.22727272727272727,20.971428571428572]
[]
["Other developments - Major",0,null,"-",null,null,null,null,null," "]
[]
["Other developments - Local",13,null,7.5054945054945055,null,null,null,null,null,"OK","OK",{"$error":"#VALUE!"}]
["Local: less than 2 months",13,1,7.5054945054945055]
["Local: more than 2 months",0,0,"-"]
[]
["EIA Developments",0,null,"-"]
["Other Consents",35,null,6.8979591836734695]
[]
["Decision Making: Applications subject to"]
["Planning/Legal Agreements",1,null,8.1428571428571423]
["Local Reviews",0,null,"-",null,null,null,null,null,"Check local review totals"]
[null,null,null,null,null,null,null,null,null,"OK"]
["Decision Making: Local Reviews and Appeals"]
[]
[null,"Total number of decisions","Original decision upheld (%)"]
["Local Reviews",0,"-"]
["Appeals to Scottish Ministers2",3,1]
[]
["Enforcement Activity"]
[]
[null,"Number"]
["Cases Taken Up",40]
["Notices Served",4]
["Reports to Procurator Fiscal",0]
["Prosecutions",0]
["Number of breaches resolved",41]
["Approved and Delegated"]
[]
["Percentage Approved",0.92125984251968507,null,null,null,null,null,null,"Approved",117,127,"Total Applications less N17"]
["Percentage Delegated",1,null,null,null,null,null,null,"Delegated",138,138,"Total Applications"]
[null,null,null,null,null,null,null,null,null,null,124,"applications received"]
["1. For a full description of the categories in this analysis please see NOTES page."]
["2. Cases where the decision was recalled and made by Ministers are not included in these figures."]
["3. Time has been removed from the decision time for 15 applications where delays were outwith the control of the local authority."]

{"sheet":"East Dunbartonshire","index":18,"n_rows":77,"n_cols":13,"rows_kept":77,"cut":false,"hidden":false,"merged":[[76,0,77,3],[2,5,2,7],[0,8,0,12],[61,0,61,3]]}
["Planning Authority Performance Statistics1,3",null,null,"East Dunbartonshire",null,null,null,null,"For Scottish Government Use during analysis\nPlease do not delete or move these columns"]
[null,null,null,"2018/19 Q3",null,null,null,null,null,"Check total number of applications"]
[null,null,null,"All Applications excluding Legacy Cases",null,null,null,null,null,193,"total apps",null,"OK"]
[null,null,null,null,null,null,null,null,null," "]
["Processing Agreements","Total Number of Decisions","% Within Agreed Timescales"]
["TOTAL",0,"-"]
["Major Applications",0,"-"]
["Local Applications",0,"-"]
["EIA  Applications",0,"-"]
["Other Applications",0,"-"]
["Applications with processing agreements are not included in the following figures."]
[null,"Total Number of Decisions","Proportion of Decisions","Average Time (Weeks)",null,null,null,null,null,"check sums to total"]
["All Major Developments",0,null,"-",null,null,null,null,null,"OK",{"$error":"#VALUE!"},{"$error":"#VALUE!"}]
["Without Legal Agreement",0,"-","-"]
["With Legal Agreement",0,"-","-"]
[null,null,null,null,null,null,null,null,null,"OK"]
["All Local Developments",169,null,7.8757396449704142,null,null,null,null,null,"OK","OK","OK"]
["Without Legal Agreement",167,0.98816568047337283,7.6937553464499571]
["With Legal Agreement",2,1.1834319526627219E-2,23.071428571428573]
["Local: less than 2 months",152,0.89940828402366868,7.1372180451127818,null,null,null,null,null,"OK","OK","OK"]
["Local: more than 2 months",17,0.10059171597633136,14.478991596638656]
[]
["All Local developments (non-householder)",23,null,10.347826086956522,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",16,0.69565217391304346,6.9910714285714288]
["Local: more than 2 months",7,0.30434782608695654,18.020408163265305]
[]
["Householder developments",146,null,7.4863013698630141,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",136,0.93150684931506844,7.1544117647058822]
["Local: more than 2 months",10,6.8493150684931503E-2,12]
[]
["Housing Developments - Major",0,null,"-"]
[]
["Housing Developments - Local",3,null,16.904761904761905,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",1,0.33333333333333331,5]
["Local: more than 2 months",2,0.66666666666666663,22.857142857142858]
[]
["Business & Industry - Major",0,null,"-"]
[]
["Business & Industry - Local",1,null,18.714285714285715,null,null,null,null,null,"OK","OK",{"$error":"#VALUE!"}]
["Local: less than 2 months",0,0,"-"]
["Local: more than 2 months",1,1,18.714285714285715]
[]
["Other developments - Major",0,null,"-",null,null,null,null,null," "]
[]
["Other developments - Local",19,null,8.8721804511278197,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",15,0.78947368421052633,7.1238095238095243]
["Local: more than 2 months",4,0.21052631578947367,15.428571428571429]
[]
["EIA Developments",0,null,"-"]
["Other Consents",24,null,6.6488095238095237]
[]
["Decision Making: Applications subject to"]
["Planning/Legal Agreements",2,null,23.071428571428573]
["Local Reviews",0,null,"-",null,null,null,null,null,"Check local review totals"]
[null,null,null,null,null,null,null,null,null,"OK"]
["Decision Making: Local Reviews and Appeals"]
[]
[null,"Total number of decisions","Original decision upheld (%)"]
["Local Reviews",0,"-"]
["Appeals to Scottish Ministers2",1,1]
[]
["Enforcement Activity"]
[]
[null,"Number"]
["Cases Taken Up",15]
["Notices Served",0]
["Reports to Procurator Fiscal",0]
["Prosecutions",0]
["Number of breaches resolved",16]
["Approved and Delegated"]
[]
["Percentage Approved",0.93785310734463279,null,null,null,null,null,null,"Approved",166,177,"Total Applications less N17"]
["Percentage Delegated",0.98445595854922274,null,null,null,null,null,null,"Delegated",190,193,"Total Applications"]
[null,null,null,null,null,null,null,null,null,null,171,"applications received"]
["1. For a full description of the categories in this analysis please see NOTES page."]
["2. Cases where the decision was recalled and made by Ministers are not included in these figures."]
["3. Time has been removed from the decision time for 40 applications where delays were outwith the control of the local authority."]

{"sheet":"East Lothian","index":19,"n_rows":77,"n_cols":14,"rows_kept":77,"cut":false,"hidden":false,"merged":[[76,0,77,3],[2,5,2,7],[0,8,0,12],[61,0,61,3],[4,9,4,12]]}
["Planning Authority Performance Statistics1,3",null,null,"East Lothian",null,null,null,null,"For Scottish Government Use during analysis\nPlease do not delete or move these columns"]
[null,null,null,"2018/19 Q3",null,null,null,null,null,"Check total number of applications"]
[null,null,null,"All Applications excluding Legacy Cases",null,null,null,null,null,297,"total apps",null,"error",295]
[null,null,null,null,null,null,null,null,null," "]
["Processing Agreements","Total Number of Decisions","% Within Agreed Timescales",null,null,null,null,null,null,"The difference of 2 in the total is due to 2 legacy cases, which is not an error."]
["TOTAL",0,"-"]
["Major Applications",0,"-"]
["Local Applications",0,"-"]
["EIA  Applications",0,"-"]
["Other Applications",0,"-"]
["Applications with processing agreements are not included in the following figures."]
[null,"Total Number of Decisions","Proportion of Decisions","Average Time (Weeks)",null,null,null,null,null,"check sums to total"]
["All Major Developments",4,null,33.928571428571431,null,null,null,null,null,"OK","OK","OK"]
["Without Legal Agreement",3,0.75,32.238095238095234]
["With Legal Agreement",1,0.25,39]
[null,null,null,null,null,null,null,null,null,"OK"]
["All Local Developments",223,null,7.9455477258167848,null,null,null,null,null,"OK","OK",{"$error":"#VALUE!"}]
["Without Legal Agreement",223,1,7.9455477258167848]
["With Legal Agreement",0,0,"-"]
["Local: less than 2 months",202,0.905829596412556,7.318246110325318,null,null,null,null,null,"OK","OK","OK"]
["Local: more than 2 months",21,9.417040358744394E-2,13.979591836734695]
[]
["All Local developments (non-householder)",78,null,8.5805860805860803,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",65,0.83333333333333337,7.1802197802197805]
["Local: more than 2 months",13,0.16666666666666666,15.582417582417582]
[]
["Householder developments",145,null,7.6039408866995073,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",137,0.94482758620689655,7.3837330552659015]
["Local: more than 2 months",8,5.5172413793103448E-2,11.375]
[]
["Housing Developments - Major",2,null,49.928571428571431]
[]
["Housing Developments - Local",17,null,11.680672268907562,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",9,0.52941176470588236,8.3492063492063497]
["Local: more than 2 months",8,0.47058823529411764,15.428571428571429]
[]
["Business & Industry - Major",0,null,"-"]
[]
["Business & Industry - Local",9,null,8.6507936507936503,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",7,0.77777777777777779,7.6530612244897958]
["Local: more than 2 months",2,0.22222222222222221,12.142857142857142]
[]
["Other developments - Major",2,null,17.928571428571427,null,null,null,null,null," "]
[]
["Other developments - Local",52,null,7.5549450549450556,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",49,0.94230769230769229,6.8979591836734695]
["Local: more than 2 months",3,5.7692307692307696E-2,18.285714285714285]
[]
["EIA Developments",0,null,"-"]
["Other Consents",68,null,6.7584033613445387]
[]
["Decision Making: Applications subject to"]
["Planning/Legal Agreements",1,null,39]
["Local Reviews",6,null,9.9047619047619033,null,null,null,null,null,"Check local review totals"]
[null,null,null,null,null,null,null,null,null,"OK"]
["Decision Making: Local Reviews and Appeals"]
[]
[null,"Total number of decisions","Original decision upheld (%)"]
["Local Reviews",6,0.33333333333333331]
["Appeals to Scottish Ministers2",0,0]
[]
["Enforcement Activity"]
[]
[null,"Number"]
["Cases Taken Up",47]
["Notices Served",11]
["Reports to Procurator Fiscal",0]
["Prosecutions",0]
["Number of breaches resolved",78]
["Approved and Delegated"]
[]
["Percentage Approved",0.96842105263157896,null,null,null,null,null,null,"Approved",276,285,"Total Applications less N17"]
["Percentage Delegated",0.98653198653198648,null,null,null,null,null,null,"Delegated",293,297,"Total Applications"]
[null,null,null,null,null,null,null,null,null,null,312,"applications received"]
["1. For a full description of the categories in this analysis please see NOTES page."]
["2. Cases where the decision was recalled and made by Ministers are not included in these figures."]
["3. Time has been removed from the decision time for 21 applications where delays were outwith the control of the local authority."]

{"sheet":"East Renfrewshire","index":20,"n_rows":77,"n_cols":13,"rows_kept":77,"cut":false,"hidden":false,"merged":[[61,0,61,3],[76,0,77,3],[2,5,2,7],[0,8,0,12]]}
["Planning Authority Performance Statistics1,3",null,null,"East Renfrewshire",null,null,null,null,"For Scottish Government Use during analysis\nPlease do not delete or move these columns"]
[null,null,null,"2018/19 Q3",null,null,null,null,null,"Check total number of applications"]
[null,null,null,"All Applications excluding Legacy Cases",null,null,null,null,null,159,"total apps",null,"OK"]
[null,null,null,null,null,null,null,null,null," "]
["Processing Agreements","Total Number of Decisions","% Within Agreed Timescales"]
["TOTAL",0,"-"]
["Major Applications",0,"-"]
["Local Applications",0,"-"]
["EIA  Applications",0,"-"]
["Other Applications",0,"-"]
["Applications with processing agreements are not included in the following figures."]
[null,"Total Number of Decisions","Proportion of Decisions","Average Time (Weeks)",null,null,null,null,null,"check sums to total"]
["All Major Developments",0,null,"-",null,null,null,null,null,"OK",{"$error":"#VALUE!"},{"$error":"#VALUE!"}]
["Without Legal Agreement",0,"-","-"]
["With Legal Agreement",0,"-","-"]
[null,null,null,null,null,null,null,null,null,"OK"]
["All Local Developments",145,null,8.398029556650247,null,null,null,null,null,"OK","OK","OK"]
["Without Legal Agreement",144,0.99310344827586206,7.8730158730158735]
["With Legal Agreement",1,6.8965517241379309E-3,84]
["Local: less than 2 months",112,0.77241379310344827,6.2576530612244898,null,null,null,null,null,"OK","OK","OK"]
["Local: more than 2 months",33,0.22758620689655173,15.662337662337663]
[]
["All Local developments (non-householder)",25,null,14.062857142857142,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",10,0.4,6.6000000000000005]
["Local: more than 2 months",15,0.6,19.038095238095242]
[]
["Householder developments",120,null,7.2178571428571425,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",102,0.85,6.2240896358543418]
["Local: more than 2 months",18,0.15,12.84920634920635]
[]
["Housing Developments - Major",0,null,"-"]
[]
["Housing Developments - Local",8,null,12.928571428571429,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",2,0.25,8.1428571428571423]
["Local: more than 2 months",6,0.75,14.523809523809524]
[]
["Business & Industry - Major",0,null,"-"]
[]
["Business & Industry - Local",2,null,6.7857142857142856,null,null,null,null,null,"OK","OK",{"$error":"#VALUE!"}]
["Local: less than 2 months",2,1,6.7857142857142856]
["Local: more than 2 months",0,0,"-"]
[]
["Other developments - Major",0,null,"-",null,null,null,null,null," "]
[]
["Other developments - Local",12,null,11.428571428571429,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",5,0.41666666666666669,6.3714285714285719]
["Local: more than 2 months",7,0.58333333333333337,15.040816326530614]
[]
["EIA Developments",0,null,"-"]
["Other Consents",14,null,4.6122448979591839]
[]
["Decision Making: Applications subject to"]
["Planning/Legal Agreements",1,null,84]
["Local Reviews",12,null,7.5357142857142856,null,null,null,null,null,"Check local review totals"]
[null,null,null,null,null,null,null,null,null,"OK"]
["Decision Making: Local Reviews and Appeals"]
[]
[null,"Total number of decisions","Original decision upheld (%)"]
["Local Reviews",12,0.33333333333333331]
["Appeals to Scottish Ministers2",3,0.66700000000000004]
[]
["Enforcement Activity"]
[]
[null,"Number"]
["Cases Taken Up",0]
["Notices Served",0]
["Reports to Procurator Fiscal",0]
["Prosecutions",0]
["Number of breaches resolved",7]
["Approved and Delegated"]
[]
["Percentage Approved",0.92052980132450335,null,null,null,null,null,null,"Approved",139,151,"Total Applications less N17"]
["Percentage Delegated",0.97484276729559749,null,null,null,null,null,null,"Delegated",155,159,"Total Applications"]
[null,null,null,null,null,null,null,null,null,null,159,"applications received"]
["1. For a full description of the categories in this analysis please see NOTES page."]
["2. Cases where the decision was recalled and made by Ministers are not included in these figures."]
["3. Time has been removed from the decision time for 3 applications where delays were outwith the control of the local authority."]

{"sheet":"City of Edinburgh","index":21,"n_rows":77,"n_cols":14,"rows_kept":77,"cut":false,"hidden":false,"merged":[[79,0,80,3],[61,0,61,3],[2,5,2,7],[0,8,0,12],[76,0,77,3]]}
["Planning Authority Performance Statistics1,3",null,null,"City of Edinburgh",null,null,null,null,"For Scottish Government Use during analysis\nPlease do not delete or move these columns"]
[null,null,null,"2018/19 Q3",null,null,null,null,null,"Check total number of applications"]
[null,null,null,"All Applications excluding Legacy Cases",null,null,null,null,null,826,"total apps",null,"error",825]
[null,null,null,null,null,null,null,null,null," "]
["Processing Agreements","Total Number of Decisions","% Within Agreed Timescales",null,null,null,null,null,null,"difference of 1 is OK it's a legacy case. "]
["TOTAL",70,0.72857142857142854]
["Major Applications",3,0.66666666666666663]
["Local Applications",48,0.72916666666666663]
["EIA  Applications",0,"-"]
["Other Applications",19,0.73684210526315785]
["Applications with processing agreements are not included in the following figures."]
[null,"Total Number of Decisions","Proportion of Decisions","Average Time (Weeks)",null,null,null,null,null,"check sums to total"]
["All Major Developments",3,null,33.285714285714285,null,null,null,null,null,"OK","OK","OK"]
["Without Legal Agreement",1,0.33333333333333331,20.142857142857142]
["With Legal Agreement",2,0.66666666666666663,39.857142857142854]
[null,null,null,null,null,null,null,null,null,"OK"]
["All Local Developments",459,null,11.629940865234984,null,null,null,null,null,"OK","OK","OK"]
["Without Legal Agreement",451,0.98257080610021785,10.067469116249603]
["With Legal Agreement",8,1.7429193899782137E-2,99.714285714285708]
["Local: less than 2 months",321,0.69934640522875813,7.40809968847352,null,null,null,null,null,"OK","OK","OK"]
["Local: more than 2 months",138,0.30065359477124182,21.450310559006208]
[]
["All Local developments (non-householder)",157,null,17.772520473157417,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",76,0.48407643312101911,7.0864661654135341]
["Local: more than 2 months",81,0.51592356687898089,27.798941798941797]
[]
["Householder developments",302,null,8.4366130558183539,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",245,0.8112582781456954,7.5078717201166185]
["Local: more than 2 months",57,0.18874172185430463,12.428571428571429]
[]
["Housing Developments - Major",1,null,8.4285714285714288]
[]
["Housing Developments - Local",33,null,30.147186147186147,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",9,0.27272727272727271,7.1587301587301591]
["Local: more than 2 months",24,0.72727272727272729,38.767857142857146]
[]
["Business & Industry - Major",0,null,"-"]
[]
["Business & Industry - Local",12,null,13.452380952380953,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",6,0.5,7.2619047619047619]
["Local: more than 2 months",6,0.5,19.642857142857142]
[]
["Other developments - Major",2,null,45.714285714285715,null,null,null,null,null," "]
[]
["Other developments - Local",100,null,14.444285714285714,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",52,0.52,7.0247252747252746]
["Local: more than 2 months",48,0.48,22.482142857142858]
[]
["EIA Developments",0,null,"-"]
["Other Consents",293,null,10.518283764017552]
[]
["Decision Making: Applications subject to"]
["Planning/Legal Agreements",10,null,87.742857142857147]
["Local Reviews",28,null,8.908163265306122,null,null,null,null,null,"Check local review totals"]
[null,null,null,null,null,null,null,null,null,"OK"]
["Decision Making: Local Reviews and Appeals"]
[]
[null,"Total number of decisions","Original decision upheld (%)"]
["Local Reviews",28,0.7142857142857143]
["Appeals to Scottish Ministers2",27,0.51900000000000002]
[]
["Enforcement Activity"]
[]
[null,"Number"]
["Cases Taken Up",163]
["Notices Served",16]
["Reports to Procurator Fiscal",0]
["Prosecutions",0]
["Number of breaches resolved",41]
["Approved and Delegated"]
[]
["Percentage Approved",0.90568475452196384,null,null,null,null,null,null,"Approved",701,774,"Total Applications less N17"]
["Percentage Delegated",0.96610169491525422,null,null,null,null,null,null,"Delegated",798,826,"Total Applications"]
[null,null,null,null,null,null,null,null,null,null,998,"applications received"]
["1. For a full description of the categories in this analysis please see NOTES page."]
["2. Cases where the decision was recalled and made by Ministers are not included in these figures."]
["3. Time has been removed from the decision time for 2 applications where delays were outwith the control of the local authority."]

{"sheet":"Falkirk","index":22,"n_rows":77,"n_cols":13,"rows_kept":77,"cut":false,"hidden":false,"merged":[[76,0,77,3],[2,5,2,7],[61,0,61,3],[0,8,0,12]]}
["Planning Authority Performance Statistics1,3",null,null,"Falkirk",null,null,null,null,"For Scottish Government Use during analysis\nPlease do not delete or move these columns"]
[null,null,null,"2018/19 Q3",null,null,null,null,null,"Check total number of applications"]
[null,null,null,"All Applications excluding Legacy Cases",null,null,null,null,null,140,"total apps",null,"error"]
[null,null,null,null,null,null,null,null,null,139,"total apps ex legacy",null,"OK"]
["Processing Agreements","Total Number of Decisions","% Within Agreed Timescales"]
["TOTAL",0,"-"]
["Major Applications",0,"-"]
["Local Applications",0,"-"]
["EIA  Applications",0,"-"]
["Other Applications",0,"-"]
["Applications with processing agreements are not included in the following figures."]
[null,"Total Number of Decisions","Proportion of Decisions","Average Time (Weeks)",null,null,null,null,null,"check sums to total"]
["All Major Developments",0,null,"-",null,null,null,null,null,"OK",{"$error":"#VALUE!"},{"$error":"#VALUE!"}]
["Without Legal Agreement",0,"-","-"]
["With Legal Agreement",0,"-","-"]
[null,null,null,null,null,null,null,null,null,"OK"]
["All Local Developments",117,null,7.4371184371184373,null,null,null,null,null,"OK","OK","OK"]
["Without Legal Agreement",116,0.99145299145299148,7.3349753694581281]
["With Legal Agreement",1,8.5470085470085479E-3,19.285714285714285]
["Local: less than 2 months",94,0.80341880341880345,5.952887537993921,null,null,null,null,null,"OK","OK","OK"]
["Local: more than 2 months",23,0.19658119658119658,13.503105590062111]
[]
["All Local developments (non-householder)",53,null,8.9164420485175206,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",36,0.67924528301886788,6.1666666666666661]
["Local: more than 2 months",17,0.32075471698113206,14.739495798319327]
[]
["Householder developments",64,null,6.2120535714285712,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",58,0.90625,5.8201970443349751]
["Local: more than 2 months",6,9.375E-2,10]
[]
["Housing Developments - Major",0,null,"-"]
[]
["Housing Developments - Local",19,null,9.2330827067669183,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",12,0.63157894736842102,6.4761904761904763]
["Local: more than 2 months",7,0.36842105263157893,13.959183673469386]
[]
["Business & Industry - Major",0,null,"-"]
[]
["Business & Industry - Local",2,null,7.2142857142857144,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",1,0.5,5.1428571428571432]
["Local: more than 2 months",1,0.5,9.2857142857142865]
[]
["Other developments - Major",0,null,"-",null,null,null,null,null," "]
[]
["Other developments - Local",32,null,8.8348214285714288,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",23,0.71875,6.0496894409937889]
["Local: more than 2 months",9,0.28125,15.952380952380953]
[]
["EIA Developments",0,null,"-"]
["Other Consents",22,null,6.3571428571428568]
[]
["Decision Making: Applications subject to"]
["Planning/Legal Agreements",1,null,19.285714285714285]
["Local Reviews",0,null,"-",null,null,null,null,null,"Check local review totals"]
[null,null,null,null,null,null,null,null,null,"OK"]
["Decision Making: Local Reviews and Appeals"]
[]
[null,"Total number of decisions","Original decision upheld (%)"]
["Local Reviews",0,"-"]
["Appeals to Scottish Ministers2",1,0]
[]
["Enforcement Activity"]
[]
[null,"Number"]
["Cases Taken Up",23]
["Notices Served",1]
["Reports to Procurator Fiscal",0]
["Prosecutions",0]
["Number of breaches resolved",3]
["Approved and Delegated"]
[]
["Percentage Approved",0.96992481203007519,null,null,null,null,null,null,"Approved",129,133,"Total Applications less N17"]
["Percentage Delegated",0.97142857142857142,null,null,null,null,null,null,"Delegated",136,140,"Total Applications"]
[null,null,null,null,null,null,null,null,null,null,164,"applications received"]
["1. For a full description of the categories in this analysis please see NOTES page."]
["2. Cases where the decision was recalled and made by Ministers are not included in these figures."]
["3. Time has been removed from the decision time for 5 applications where delays were outwith the control of the local authority."]

{"sheet":"Fife","index":23,"n_rows":77,"n_cols":13,"rows_kept":77,"cut":false,"hidden":false,"merged":[[61,0,61,3],[76,0,77,3],[2,5,2,7],[0,8,0,12]]}
["Planning Authority Performance Statistics1,3",null,null,"Fife ",null,null,null,null,"For Scottish Government Use during analysis\nPlease do not delete or move these columns"]
[null,null,null,"2018/19 Q3",null,null,null,null,null,"Check total number of applications"]
[null,null,null,"All Applications excluding Legacy Cases",null,null,null,null,null,506,"total apps",null,"OK"]
[null,null,null,null,null,null,null,null,null," "]
["Processing Agreements","Total Number of Decisions","% Within Agreed Timescales"]
["TOTAL",111,0.72972972972972971]
["Major Applications",0,"-"]
["Local Applications",90,0.72222222222222221]
["EIA  Applications",0,"-"]
["Other Applications",21,0.76190476190476186]
["Applications with processing agreements are not included in the following figures."]
[null,"Total Number of Decisions","Proportion of Decisions","Average Time (Weeks)",null,null,null,null,null,"check sums to total"]
["All Major Developments",1,null,13.285714285714286,null,null,null,null,null,"OK","OK",{"$error":"#VALUE!"}]
["Without Legal Agreement",1,1,13.285714285714286]
["With Legal Agreement",0,0,"-"]
[null,null,null,null,null,null,null,null,null,"OK"]
["All Local Developments",285,null,7.9839598997493733,null,null,null,null,null,"OK","OK",{"$error":"#VALUE!"}]
["Without Legal Agreement",285,1,7.9839598997493733]
["With Legal Agreement",0,0,"-"]
["Local: less than 2 months",214,0.75087719298245614,6.6762349799732972,null,null,null,null,null,"OK","OK","OK"]
["Local: more than 2 months",71,0.24912280701754386,11.925553319919517]
[]
["All Local developments (non-householder)",103,null,9.1109570041608876,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",63,0.61165048543689315,7.029478458049887]
["Local: more than 2 months",40,0.38834951456310679,12.389285714285714]
[]
["Householder developments",182,null,7.3461538461538458,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",151,0.82967032967032972,6.5288552507095554]
["Local: more than 2 months",31,0.17032967032967034,11.327188940092167]
[]
["Housing Developments - Major",0,null,"-"]
[]
["Housing Developments - Local",24,null,9.886904761904761,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",12,0.5,7.4642857142857144]
["Local: more than 2 months",12,0.5,12.30952380952381]
[]
["Business & Industry - Major",0,null,"-"]
[]
["Business & Industry - Local",2,null,8.2857142857142865,null,null,null,null,null,"OK","OK",{"$error":"#VALUE!"}]
["Local: less than 2 months",2,1,8.2857142857142865]
["Local: more than 2 months",0,0,"-"]
[]
["Other developments - Major",1,null,13.285714285714286,null,null,null,null,null," "]
[]
["Other developments - Local",74,null,8.6833976833976827,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",48,0.64864864864864868,6.8630952380952381]
["Local: more than 2 months",26,0.35135135135135137,12.043956043956044]
[]
["EIA Developments",0,null,"-"]
["Other Consents",109,null,5.199213630406291]
[]
["Decision Making: Applications subject to"]
["Planning/Legal Agreements",0,null,"-"]
["Local Reviews",4,null,13.75,null,null,null,null,null,"Check local review totals"]
[null,null,null,null,null,null,null,null,null,"OK"]
["Decision Making: Local Reviews and Appeals"]
[]
[null,"Total number of decisions","Original decision upheld (%)"]
["Local Reviews",4,0.5]
["Appeals to Scottish Ministers2",3,0.66700000000000004]
[]
["Enforcement Activity"]
[]
[null,"Number"]
["Cases Taken Up",7]
["Notices Served",0]
["Reports to Procurator Fiscal",0]
["Prosecutions",0]
["Number of breaches resolved",21]
["Approved and Delegated"]
[]
["Percentage Approved",0.96710526315789469,null,null,null,null,null,null,"Approved",441,456,"Total Applications less N17"]
["Percentage Delegated",0.98023715415019763,null,null,null,null,null,null,"Delegated",496,506,"Total Applications"]
[null,null,null,null,null,null,null,null,null,null,508,"applications received"]
["1. For a full description of the categories in this analysis please see NOTES page."]
["2. Cases where the decision was recalled and made by Ministers are not included in these figures."]
["3. Time has been removed from the decision time for 10 applications where delays were outwith the control of the local authority."]

{"sheet":"Glasgow City","index":24,"n_rows":77,"n_cols":13,"rows_kept":77,"cut":false,"hidden":false,"merged":[[2,5,2,7],[61,0,61,3],[76,0,77,3],[0,8,0,12],[1,8,1,12]]}
["Planning Authority Performance Statistics1,3",null,null,"Glasgow City",null,null,null,null,"For Scottish Government Use during analysis\nPlease do not delete or move these columns"]
[null,null,null,"2018/19 Q3",null,null,null,null,"Check total number of applications"]
[null,null,null,"All Applications excluding Legacy Cases",null,null,null,null,null,689,"total apps",null,"OK"]
[null,null,null,null,null,null,null,null,null," "]
["Processing Agreements","Total Number of Decisions","% Within Agreed Timescales"]
["TOTAL",28,0.5714285714285714]
["Major Applications",0,"-"]
["Local Applications",18,0.61111111111111116]
["EIA  Applications",0,"-"]
["Other Applications",10,0.5]
["Applications with processing agreements are not included in the following figures."]
[null,"Total Number of Decisions","Proportion of Decisions","Average Time (Weeks)",null,null,null,null,null,"check sums to total"]
["All Major Developments",17,null,19.983193277310924,null,null,null,null,null,"OK","OK","OK"]
["Without Legal Agreement",9,0.52941176470588236,13.380952380952381]
["With Legal Agreement",8,0.47058823529411764,27.410714285714285]
[null,null,null,null,null,null,null,null,null,"OK"]
["All Local Developments",419,null,9.1916126832594625,null,null,null,null,null,"OK","OK","OK"]
["Without Legal Agreement",410,0.97852028639618138,8.8710801393728218]
["With Legal Agreement",9,2.1479713603818614E-2,23.793650793650791]
["Local: less than 2 months",317,0.75656324582338907,6.5619648490310949,null,null,null,null,null,"OK","OK","OK"]
["Local: more than 2 months",102,0.24343675417661098,17.364145658263304]
[]
["All Local developments (non-householder)",234,null,11.142857142857142,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",142,0.60683760683760679,6.7162977867203226]
["Local: more than 2 months",92,0.39316239316239315,17.975155279503106]
[]
["Householder developments",185,null,6.7235521235521238,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",175,0.94594594594594594,6.4367346938775514]
["Local: more than 2 months",10,5.4054054054054057E-2,11.742857142857144]
[]
["Housing Developments - Major",9,null,23.047619047619047]
[]
["Housing Developments - Local",59,null,13.179176755447942,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",31,0.52542372881355937,6.7926267281105988]
["Local: more than 2 months",28,0.47457627118644069,20.25]
[]
["Business & Industry - Major",3,null,16.380952380952383]
[]
["Business & Industry - Local",36,null,9.261904761904761,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",24,0.66666666666666663,6.4523809523809517]
["Local: more than 2 months",12,0.33333333333333331,14.880952380952381]
[]
["Other developments - Major",5,null,16.62857142857143,null,null,null,null,null," "]
[]
["Other developments - Local",128,null,10.540178571428571,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",80,0.625,6.6928571428571431]
["Local: more than 2 months",48,0.375,16.952380952380953]
[]
["EIA Developments",0,null,"-"]
["Other Consents",225,null,9.0634920634920633]
[]
["Decision Making: Applications subject to"]
["Planning/Legal Agreements",17,null,25.495798319327729]
["Local Reviews",7,null,10.530612244897958,null,null,null,null,null,"Check local review totals"]
[null,null,null,null,null,null,null,null,null,"OK"]
["Decision Making: Local Reviews and Appeals"]
[]
[null,"Total number of decisions","Original decision upheld (%)"]
["Local Reviews",7,0.5714285714285714]
["Appeals to Scottish Ministers2",4,0]
[]
["Enforcement Activity"]
[]
[null,"Number"]
["Cases Taken Up",148]
["Notices Served",14]
["Reports to Procurator Fiscal",0]
["Prosecutions",0]
["Number of breaches resolved",89]
["Approved and Delegated"]
[]
["Percentage Approved",0.8917293233082707,null,null,null,null,null,null,"Approved",593,665,"Total Applications less N17"]
["Percentage Delegated",0.98258345428156746,null,null,null,null,null,null,"Delegated",677,689,"Total Applications"]
[null,null,null,null,null,null,null,null,null,null,689,"applications received"]
["1. For a full description of the categories in this analysis please see NOTES page."]
["2. Cases where the decision was recalled and made by Ministers are not included in these figures."]
["3. Time has been removed from the decision time for 88 applications where delays were outwith the control of the local authority."]

{"sheet":"Highland","index":25,"n_rows":77,"n_cols":13,"rows_kept":77,"cut":false,"hidden":false,"merged":[[61,0,61,3],[76,0,77,3],[2,5,2,7],[0,8,0,12]]}
["Planning Authority Performance Statistics1,3",null,null,"Highland",null,null,null,null,"For Scottish Government Use during analysis\nPlease do not delete or move these columns"]
[null,null,null,"2018/19 Q3",null,null,null,null,null,"Check total number of applications"]
[null,null,null,"All Applications excluding Legacy Cases",null,null,null,null,null,763,"total apps",null,"OK"]
[null,null,null,null,null,null,null,null,null," "]
["Processing Agreements","Total Number of Decisions","% Within Agreed Timescales"]
["TOTAL",17,0.58823529411764708]
["Major Applications",6,0.66666666666666663]
["Local Applications",11,0.54545454545454541]
["EIA  Applications",0,"-"]
["Other Applications",0,"-"]
["Applications with processing agreements are not included in the following figures."]
[null,"Total Number of Decisions","Proportion of Decisions","Average Time (Weeks)",null,null,null,null,null,"check sums to total"]
["All Major Developments",1,null,36.857142857142854,null,null,null,null,null,"OK","OK",{"$error":"#VALUE!"}]
["Without Legal Agreement",1,1,36.857142857142854]
["With Legal Agreement",0,0,"-"]
[null,null,null,null,null,null,null,null,null,"OK"]
["All Local Developments",630,null,10.469387755102042,null,null,null,null,null,"OK","OK","OK"]
["Without Legal Agreement",619,0.98253968253968249,10.086083544888069]
["With Legal Agreement",11,1.7460317460317461E-2,32.038961038961041]
["Local: less than 2 months",429,0.68095238095238098,6.2604062604062607,null,null,null,null,null,"OK","OK","OK"]
["Local: more than 2 months",201,0.31904761904761902,19.452736318407961]
[]
["All Local developments (non-householder)",455,null,12.113029827315541,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",268,0.58901098901098903,6.6231343283582094]
["Local: more than 2 months",187,0.41098901098901097,19.980901451489689]
[]
["Householder developments",175,null,6.1959183673469393,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",161,0.92,5.6566104702750666]
["Local: more than 2 months",14,0.08,12.397959183673469]
[]
["Housing Developments - Major",0,null,"-"]
[]
["Housing Developments - Local",233,null,13.61925199264255,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",124,0.53218884120171672,6.7465437788018434]
["Local: more than 2 months",109,0.46781115879828328,21.437745740498034]
[]
["Business & Industry - Major",0,null,"-"]
[]
["Business & Industry - Local",54,null,11.116402116402115,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",32,0.59259259259259256,6.8839285714285712]
["Local: more than 2 months",22,0.40740740740740738,17.272727272727273]
[]
["Other developments - Major",0,null,"-",null,null,null,null,null," "]
[]
["Other developments - Local",143,null,10.086913086913087,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",98,0.68531468531468531,6.4052478134110791]
["Local: more than 2 months",45,0.31468531468531469,18.104761904761904]
[]
["EIA Developments",1,null,26.857142857142858]
["Other Consents",114,null,6.4624060150375939]
[]
["Decision Making: Applications subject to"]
["Planning/Legal Agreements",13,null,28.197802197802197]
["Local Reviews",4,null,8.6428571428571423,null,null,null,null,null,"Check local review totals"]
[null,null,null,null,null,null,null,null,null,"OK"]
["Decision Making: Local Reviews and Appeals"]
[]
[null,"Total number of decisions","Original decision upheld (%)"]
["Local Reviews",4,0.5]
["Appeals to Scottish Ministers2",6,0.5]
[]
["Enforcement Activity"]
[]
[null,"Number"]
["Cases Taken Up",31]
["Notices Served",15]
["Reports to Procurator Fiscal",0]
["Prosecutions",0]
["Number of breaches resolved",109]
["Approved and Delegated"]
[]
["Percentage Approved",0.9536516853932584,null,null,null,null,null,null,"Approved",679,712,"Total Applications less N17"]
["Percentage Delegated",0.95674967234600261,null,null,null,null,null,null,"Delegated",730,763,"Total Applications"]
[null,null,null,null,null,null,null,null,null,null,1122,"applications received"]
["1. For a full description of the categories in this analysis please see NOTES page."]
["2. Cases where the decision was recalled and made by Ministers are not included in these figures."]
["3. Time has been removed from the decision time for 35 applications where delays were outwith the control of the local authority."]

{"sheet":"Inverclyde","index":26,"n_rows":77,"n_cols":13,"rows_kept":77,"cut":false,"hidden":false,"merged":[[61,0,61,3],[76,0,77,3],[2,5,2,7],[0,8,0,12]]}
["Planning Authority Performance Statistics1,3",null,null,"Inverclyde",null,null,null,null,"For Scottish Government Use during analysis\nPlease do not delete or move these columns"]
[null,null,null,"2018/19 Q3",null,null,null,null,null,"Check total number of applications"]
[null,null,null,"All Applications excluding Legacy Cases",null,null,null,null,null,78,"total apps",null,"OK"]
[null,null,null,null,null,null,null,null,null," "]
["Processing Agreements","Total Number of Decisions","% Within Agreed Timescales"]
["TOTAL",0,"-"]
["Major Applications",0,"-"]
["Local Applications",0,"-"]
["EIA  Applications",0,"-"]
["Other Applications",0,"-"]
["Applications with processing agreements are not included in the following figures."]
[null,"Total Number of Decisions","Proportion of Decisions","Average Time (Weeks)",null,null,null,null,null,"check sums to total"]
["All Major Developments",0,null,"-",null,null,null,null,null,"OK",{"$error":"#VALUE!"},{"$error":"#VALUE!"}]
["Without Legal Agreement",0,"-","-"]
["With Legal Agreement",0,"-","-"]
[null,null,null,null,null,null,null,null,null,"OK"]
["All Local Developments",59,null,7.1186440677966099,null,null,null,null,null,"OK","OK",{"$error":"#VALUE!"}]
["Without Legal Agreement",59,1,7.1186440677966099]
["With Legal Agreement",0,0,"-"]
["Local: less than 2 months",49,0.83050847457627119,5.9679300291545188,null,null,null,null,null,"OK","OK","OK"]
["Local: more than 2 months",10,0.16949152542372881,12.757142857142856]
[]
["All Local developments (non-householder)",23,null,8.6521739130434785,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",18,0.78260869565217395,6.6269841269841265]
["Local: more than 2 months",5,0.21739130434782608,15.942857142857141]
[]
["Householder developments",36,null,6.1388888888888884,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",31,0.86111111111111116,5.5852534562211975]
["Local: more than 2 months",5,0.1388888888888889,9.5714285714285712]
[]
["Housing Developments - Major",0,null,"-"]
[]
["Housing Developments - Local",4,null,8.1428571428571423,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",3,0.75,6.1904761904761907]
["Local: more than 2 months",1,0.25,14]
[]
["Business & Industry - Major",0,null,"-"]
[]
["Business & Industry - Local",1,null,7.5714285714285712,null,null,null,null,null,"OK","OK",{"$error":"#VALUE!"}]
["Local: less than 2 months",1,1,7.5714285714285712]
["Local: more than 2 months",0,0,"-"]
[]
["Other developments - Major",0,null,"-",null,null,null,null,null," "]
[]
["Other developments - Local",18,null,8.825396825396826,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",14,0.77777777777777779,6.6530612244897958]
["Local: more than 2 months",4,0.22222222222222221,16.428571428571427]
[]
["EIA Developments",0,null,"-"]
["Other Consents",19,null,6.3157894736842106]
[]
["Decision Making: Applications subject to"]
["Planning/Legal Agreements",0,null,"-"]
["Local Reviews",2,null,13.285714285714286,null,null,null,null,null,"Check local review totals"]
[null,null,null,null,null,null,null,null,null,"OK"]
["Decision Making: Local Reviews and Appeals"]
[]
[null,"Total number of decisions","Original decision upheld (%)"]
["Local Reviews",2,0]
["Appeals to Scottish Ministers2",0]
[]
["Enforcement Activity"]
[]
[null,"Number"]
["Cases Taken Up",4]
["Notices Served",0]
["Reports to Procurator Fiscal",0]
["Prosecutions",0]
["Number of breaches resolved",3]
["Approved and Delegated"]
[]
["Percentage Approved",0.95890410958904104,null,null,null,null,null,null,"Approved",70,73,"Total Applications less N17"]
["Percentage Delegated",1,null,null,null,null,null,null,"Delegated",78,78,"Total Applications"]
[null,null,null,null,null,null,null,null,null,null,88,"applications received"]
["1. For a full description of the categories in this analysis please see NOTES page."]
["2. Cases where the decision was recalled and made by Ministers are not included in these figures."]
["3. Time has been removed from the decision time for 5 applications where delays were outwith the control of the local authority."]

{"sheet":"Loch Lomond","index":27,"n_rows":83,"n_cols":13,"rows_kept":83,"cut":false,"hidden":false,"merged":[[79,0,80,3],[61,0,61,3],[76,0,77,3],[2,5,2,7],[0,8,0,12]]}
["Planning Authority Performance Statistics1,3",null,null,"Loch Lomond and The Trossachs",null,null,null,null,"For Scottish Government Use during analysis\nPlease do not delete or move these columns"]
[null,null,null,"2018/19 Q3",null,null,null,null,null,"Check total number of applications"]
[null,null,null,"All Applications excluding Legacy Cases",null,null,null,null,null,75,"total apps",null,"OK"]
[null,null,null,null,null,null,null,null,null," "]
["Processing Agreements","Total Number of Decisions","% Within Agreed Timescales"]
["TOTAL",3,0.66666666666666663]
["Major Applications",1,1]
["Local Applications",2,0.5]
["EIA  Applications",0,"-"]
["Other Applications",0,"-"]
["Applications with processing agreements are not included in the following figures."]
[null,"Total Number of Decisions","Proportion of Decisions","Average Time (Weeks)",null,null,null,null,null,"check sums to total"]
["All Major Developments",0,null,"-",null,null,null,null,null,"OK",{"$error":"#VALUE!"},{"$error":"#VALUE!"}]
["Without Legal Agreement",0,"-","-"]
["With Legal Agreement",0,"-","-"]
[null,null,null,null,null,null,null,null,null,"OK"]
["All Local Developments",59,null,12.423728813559322,null,null,null,null,null,"OK","OK",{"$error":"#VALUE!"}]
["Without Legal Agreement",59,1,12.423728813559322]
["With Legal Agreement",0,0,"-"]
["Local: less than 2 months",17,0.28813559322033899,6.7983193277310923,null,null,null,null,null,"OK","OK","OK"]
["Local: more than 2 months",42,0.71186440677966101,14.700680272108842]
[]
["All Local developments (non-householder)",44,null,13.461038961038962,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",11,0.25,6.7532467532467537]
["Local: more than 2 months",33,0.75,15.696969696969697]
[]
["Householder developments",15,null,9.3809523809523814,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",6,0.4,6.8809523809523805]
["Local: more than 2 months",9,0.6,11.047619047619047]
[]
["Housing Developments - Major",0,null,"-"]
[]
["Housing Developments - Local",5,null,16.142857142857142,null,null,null,null,null,"OK","OK",{"$error":"#VALUE!"}]
["Local: less than 2 months",0,0,"-"]
["Local: more than 2 months",5,1,16.142857142857142]
[]
["Business & Industry - Major",0,null,"-"]
[]
["Business & Industry - Local",4,null,7.75,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",2,0.5,6.4285714285714288]
["Local: more than 2 months",2,0.5,9.0714285714285712]
[]
["Other developments - Major",0,null,"-",null,null,null,null,null," "]
[]
["Other developments - Local",29,null,13.22167487684729,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",7,0.2413793103448276,6.6530612244897958]
["Local: more than 2 months",22,0.75862068965517238,15.311688311688313]
[]
["EIA Developments",0,null,"-"]
["Other Consents",13,null,11.846153846153845]
[]
["Decision Making: Applications subject to"]
["Planning/Legal Agreements",0,null,"-"]
["Local Reviews",0,null,"-",null,null,null,null,null,"Check local review totals"]
[null,null,null,null,null,null,null,null,null,"OK"]
["Decision Making: Local Reviews and Appeals"]
[]
[null,"Total number of decisions","Original decision upheld (%)"]
["Local Reviews",0,"-"]
["Appeals to Scottish Ministers2",0,"-"]
[]
["Enforcement Activity"]
[]
[null,"Number"]
["Cases Taken Up",13]
["Notices Served",1]
["Reports to Procurator Fiscal",0]
["Prosecutions",0]
["Number of breaches resolved",4]
["Approved and Delegated"]
[]
["Percentage Approved",0.95833333333333337,null,null,null,null,null,null,"Approved",69,72,"Total Applications less N17"]
["Percentage Delegated",0.93333333333333335,null,null,null,null,null,null,"Delegated",70,75,"Total Applications"]
[null,null,null,null,null,null,null,null,null,null,85,"applications received"]
["1. For a full description of the categories in this analysis please see NOTES page."]
["2. Cases where the decision was recalled and made by Ministers are not included in these figures."]
["3. Time has been removed from the decision time for 25 applications where delays were outwith the control of the local authority."]
[]
["OR"]
["3. Details of delays that are outwith the control of the local authority are not available. This could mean some average decision times may be higher than otherwise.       \n       \n"]
[]
["OR"]
["3. Time has not been removed from the decision time for any applications."]

{"sheet":"Midlothian","index":28,"n_rows":77,"n_cols":13,"rows_kept":77,"cut":false,"hidden":false,"merged":[[76,0,77,3]]}
["Planning Authority Performance Statistics1,3",null,null,"Midlothian",null,null,null,null,"For Scottish Government Use during analysis\nPlease do not delete or move these columns"]
[null,null,null,"2018/19 Q3",null,null,null,null,null,"Check total number of applications"]
[null,null,null,"All Applications excluding Legacy Cases",null,null,null,null,null,152,"total apps",null,"OK"]
[null,null,null,null,null,null,null,null,null," "]
["Processing Agreements","Total Number of Decisions","% Within Agreed Timescales"]
["TOTAL",0,"-"]
["Major Applications",0,"-"]
["Local Applications",0,"-"]
["EIA  Applications",0,"-"]
["Other Applications",0,"-"]
["Applications with processing agreements are not included in the following figures."]
[null,"Total Number of Decisions","Proportion of Decisions","Average Time (Weeks)",null,null,null,null,null,"check sums to total"]
["All Major Developments",1,null,28.571428571428573,null,null,null,null,null,"OK","OK",{"$error":"#VALUE!"}]
["Without Legal Agreement",1,1,28.571428571428573]
["With Legal Agreement",0,0,"-"]
[null,null,null,null,null,null,null,null,null,"OK"]
["All Local Developments",122,null,8.9566744730679151,null,null,null,null,null,"OK","OK","OK"]
["Without Legal Agreement",120,0.98360655737704916,8.4821428571428577]
["With Legal Agreement",2,1.6393442622950821E-2,37.428571428571431]
["Local: less than 2 months",100,0.81967213114754101,6.7028571428571428,null,null,null,null,null,"OK","OK","OK"]
["Local: more than 2 months",22,0.18032786885245902,19.2012987012987]
[]
["All Local developments (non-householder)",60,null,11.702380952380953,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",39,0.65,7.4358974358974361]
["Local: more than 2 months",21,0.35,19.625850340136054]
[]
["Householder developments",62,null,6.2995391705069119,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",61,0.9838709677419355,6.2341920374707263]
["Local: more than 2 months",1,1.6129032258064516E-2,10.285714285714286]
[]
["Housing Developments - Major",0,null,"-"]
[]
["Housing Developments - Local",17,null,15.302521008403362,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",7,0.41176470588235292,8.2857142857142865]
["Local: more than 2 months",10,0.58823529411764708,20.214285714285715]
[]
["Business & Industry - Major",0,null,"-"]
[]
["Business & Industry - Local",2,null,5.5714285714285712,null,null,null,null,null,"OK","OK",{"$error":"#VALUE!"}]
["Local: less than 2 months",2,1,5.5714285714285712]
["Local: more than 2 months",0,0,"-"]
[]
["Other developments - Major",1,null,28.571428571428573,null,null,null,null,null," "]
[]
["Other developments - Local",35,null,9.8938775510204078,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",26,0.74285714285714288,7.2582417582417582]
["Local: more than 2 months",9,0.25714285714285712,17.50793650793651]
[]
["EIA Developments",0,null,"-"]
["Other Consents",29,null,5.5566502463054182]
[]
["Decision Making: Applications subject to"]
["Planning/Legal Agreements",2,null,37.428571428571431]
["Local Reviews",4,null,11.142857142857142,null,null,null,null,null,"Check local review totals"]
[null,null,null,null,null,null,null,null,null,"OK"]
["Decision Making: Local Reviews and Appeals"]
[]
[null,"Total number of decisions","Original decision upheld (%)"]
["Local Reviews",4,0.25]
["Appeals to Scottish Ministers2",1,1]
[]
["Enforcement Activity"]
[]
[null,"Number"]
["Cases Taken Up",39]
["Notices Served",1]
["Reports to Procurator Fiscal",0]
["Prosecutions",0]
["Number of breaches resolved",57]
["Approved and Delegated"]
[]
["Percentage Approved",0.86986301369863017,null,null,null,null,null,null,"Approved",127,146,"Total Applications less N17"]
["Percentage Delegated",0.98026315789473684,null,null,null,null,null,null,"Delegated",149,152,"Total Applications"]
[null,null,null,null,null,null,null,null,null,null,224,"applications received"]
["1. For a full description of the categories in this analysis please see NOTES page."]
["2. Cases where the decision was recalled and made by Ministers are not included in these figures."]
["3. Time has been removed from the decision time for 12 applications where delays were outwith the control of the local authority."]

{"sheet":"Moray","index":29,"n_rows":77,"n_cols":13,"rows_kept":77,"cut":false,"hidden":false,"merged":[[76,0,77,3],[2,5,2,7],[0,8,0,12],[61,0,61,3]]}
["Planning Authority Performance Statistics1,3",null,null,"Moray",null,null,null,null,"For Scottish Government Use during analysis\nPlease do not delete or move these columns"]
[null,null,null,"2018/19 Q3",null,null,null,null,null,"Check total number of applications"]
[null,null,null,"All Applications excluding Legacy Cases",null,null,null,null,null,159,"total apps",null,"OK"]
[null,null,null,null,null,null,null,null,null," "]
["Processing Agreements","Total Number of Decisions","% Within Agreed Timescales"]
["TOTAL",2,0]
["Major Applications",0,"-"]
["Local Applications",2,0]
["EIA  Applications",0,"-"]
["Other Applications",0,"-"]
["Applications with processing agreements are not included in the following figures."]
[null,"Total Number of Decisions","Proportion of Decisions","Average Time (Weeks)",null,null,null,null,null,"check sums to total"]
["All Major Developments",2,null,10,null,null,null,null,null,"OK","OK",{"$error":"#VALUE!"}]
["Without Legal Agreement",2,1,10]
["With Legal Agreement",0,0,"-"]
[null,null,null,null,null,null,null,null,null,"OK"]
["All Local Developments",132,null,5.9545454545454541,null,null,null,null,null,"OK","OK",{"$error":"#VALUE!"}]
["Without Legal Agreement",132,1,5.9545454545454541]
["With Legal Agreement",0,0,"-"]
["Local: less than 2 months",124,0.93939393939393945,5.6647465437788025,null,null,null,null,null,"OK","OK","OK"]
["Local: more than 2 months",8,6.0606060606060608E-2,10.446428571428571]
[]
["All Local developments (non-householder)",79,null,6.3725135623869802,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",71,0.89873417721518989,5.9134808853118708]
["Local: more than 2 months",8,0.10126582278481013,10.446428571428571]
[]
["Householder developments",53,null,5.3315363881401625,null,null,null,null,null,"OK","OK",{"$error":"#VALUE!"}]
["Local: less than 2 months",53,1,5.3315363881401625]
["Local: more than 2 months",0,0,"-"]
[]
["Housing Developments - Major",0,null,"-"]
[]
["Housing Developments - Local",51,null,6.2773109243697478,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",46,0.90196078431372551,5.7981366459627335]
["Local: more than 2 months",5,9.8039215686274508E-2,10.685714285714285]
[]
["Business & Industry - Major",1,null,3.2857142857142856]
[]
["Business & Industry - Local",22,null,6.5454545454545459,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",20,0.90909090909090906,6.1357142857142861]
["Local: more than 2 months",2,9.0909090909090912E-2,10.642857142857142]
[]
["Other developments - Major",1,null,16.714285714285715,null,null,null,null,null," "]
[]
["Other developments - Local",5,null,6.2571428571428571,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",4,0.8,5.6071428571428568]
["Local: more than 2 months",1,0.2,8.8571428571428577]
[]
["EIA Developments",0,null,"-"]
["Other Consents",23,null,6.2422360248447211]
[]
["Decision Making: Applications subject to"]
["Planning/Legal Agreements",0,null,"-"]
["Local Reviews",5,null,8.2857142857142865,null,null,null,null,null,"Check local review totals"]
[null,null,null,null,null,null,null,null,null,"OK"]
["Decision Making: Local Reviews and Appeals"]
[]
[null,"Total number of decisions","Original decision upheld (%)"]
["Local Reviews",5,0.4]
["Appeals to Scottish Ministers2",0,"-"]
[]
["Enforcement Activity"]
[]
[null,"Number"]
["Cases Taken Up",64]
["Notices Served",5]
["Reports to Procurator Fiscal",0]
["Prosecutions",0]
["Number of breaches resolved",45]
["Approved and Delegated"]
[]
["Percentage Approved",0.9426751592356688,null,null,null,null,null,null,"Approved",148,157,"Total Applications less N17"]
["Percentage Delegated",0.98742138364779874,null,null,null,null,null,null,"Delegated",157,159,"Total Applications"]
[null,null,null,null,null,null,null,null,null,null,169,"applications received"]
["1. For a full description of the categories in this analysis please see NOTES page."]
["2. Cases where the decision was recalled and made by Ministers are not included in these figures."]
["3. Time has been removed from the decision time for 37 applications where delays were outwith the control of the local authority."]

{"sheet":"Na h-Eileanan Siar","index":30,"n_rows":77,"n_cols":13,"rows_kept":77,"cut":false,"hidden":false,"merged":[[2,5,2,7],[0,8,0,12],[61,0,61,3]]}
["Planning Authority Performance Statistics1,3",null,null,"Na h-Eileanan Siar",null,null,null,null,"For Scottish Government Use during analysis\nPlease do not delete or move these columns"]
[null,null,null,"2018/19 Q3",null,null,null,null,null,"Check total number of applications"]
[null,null,null,"All Applications excluding Legacy Cases",null,null,null,null,null,100,"total apps",null,"OK"]
[null,null,null,null,null,null,null,null,null," "]
["Processing Agreements","Total Number of Decisions","% Within Agreed Timescales"]
["TOTAL",1,1]
["Major Applications",1,1]
["Local Applications",0,"-"]
["EIA  Applications",0,"-"]
["Other Applications",0,"-"]
["Applications with processing agreements are not included in the following figures."]
[null,"Total Number of Decisions","Proportion of Decisions","Average Time (Weeks)",null,null,null,null,null,"check sums to total"]
["All Major Developments",0,null,"-",null,null,null,null,null,"OK",{"$error":"#VALUE!"},{"$error":"#VALUE!"}]
["Without Legal Agreement",0,"-","-"]
["With Legal Agreement",0,"-","-"]
[null,null,null,null,null,null,null,null,null,"OK"]
["All Local Developments",83,null,7.5628227194492252,null,null,null,null,null,"OK","OK",{"$error":"#VALUE!"}]
["Without Legal Agreement",83,1,7.5628227194492252]
["With Legal Agreement",0,0,"-"]
["Local: less than 2 months",68,0.81927710843373491,6.4852941176470589,null,null,null,null,null,"OK","OK","OK"]
["Local: more than 2 months",15,0.18072289156626506,12.447619047619048]
[]
["All Local developments (non-householder)",66,null,8.0887445887445892,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",51,0.77272727272727271,6.8067226890756301]
["Local: more than 2 months",15,0.22727272727272727,12.447619047619048]
[]
["Householder developments",17,null,5.5210084033613445,null,null,null,null,null,"OK","OK",{"$error":"#VALUE!"}]
["Local: less than 2 months",17,1,5.5210084033613445]
["Local: more than 2 months",0,0,"-"]
[]
["Housing Developments - Major",0,null,"-"]
[]
["Housing Developments - Local",32,null,8.1964285714285712,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",23,0.71875,6.7701863354037268]
["Local: more than 2 months",9,0.28125,11.84126984126984]
[]
["Business & Industry - Major",0,null,"-"]
[]
["Business & Industry - Local",8,null,8.0892857142857135,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",6,0.75,6.9523809523809517]
["Local: more than 2 months",2,0.25,11.5]
[]
["Other developments - Major",0,null,"-",null,null,null,null,null," "]
[]
["Other developments - Local",22,null,8.1428571428571423,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",18,0.81818181818181823,6.7777777777777777]
["Local: more than 2 months",4,0.18181818181818182,14.285714285714286]
[]
["EIA Developments",0,null,"-"]
["Other Consents",16,null,5.9642857142857144]
[]
["Decision Making: Applications subject to"]
["Planning/Legal Agreements",0,null,"-"]
["Local Reviews",0,null,"-",null,null,null,null,null,"Check local review totals"]
[null,null,null,null,null,null,null,null,null,"OK"]
["Decision Making: Local Reviews and Appeals"]
[]
[null,"Total number of decisions","Original decision upheld (%)"]
["Local Reviews",0,"-"]
["Appeals to Scottish Ministers2",0,"-"]
[]
["Enforcement Activity"]
[]
[null,"Number"]
["Cases Taken Up",2]
["Notices Served",0]
["Reports to Procurator Fiscal",1]
["Prosecutions",0]
["Number of breaches resolved",0]
["Approved and Delegated"]
[]
["Percentage Approved",1,null,null,null,null,null,null,"Approved",86,86,"Total Applications less N17"]
["Percentage Delegated",0.96,null,null,null,null,null,null,"Delegated",96,100,"Total Applications"]
[null,null,null,null,null,null,null,null,null,null,94,"applications received"]
["1. For a full description of the categories in this analysis please see NOTES page."]
["2. Cases where the decision was recalled and made by Ministers are not included in these figures."]
["3. Time has not been removed from the decision time for any applications."]

{"sheet":"North Ayrshire","index":31,"n_rows":77,"n_cols":13,"rows_kept":77,"cut":false,"hidden":false,"merged":[[61,0,61,3],[76,0,77,3],[2,5,2,7],[0,8,0,12]]}
["Planning Authority Performance Statistics1,3",null,null,"North Ayrshire",null,null,null,null,"For Scottish Government Use during analysis\nPlease do not delete or move these columns"]
[null,null,null,"2018/19 Q3",null,null,null,null,null,"Check total number of applications"]
[null,null,null,"All Applications excluding Legacy Cases",null,null,null,null,null,127,"total apps",null,"OK"]
[null,null,null,null,null,null,null,null,null," "]
["Processing Agreements","Total Number of Decisions","% Within Agreed Timescales"]
["TOTAL",0,"-"]
["Major Applications",0,"-"]
["Local Applications",0,"-"]
["EIA  Applications",0,"-"]
["Other Applications",0,"-"]
["Applications with processing agreements are not included in the following figures."]
[null,"Total Number of Decisions","Proportion of Decisions","Average Time (Weeks)",null,null,null,null,null,"check sums to total"]
["All Major Developments",0,null,"-",null,null,null,null,null,"OK",{"$error":"#VALUE!"},{"$error":"#VALUE!"}]
["Without Legal Agreement",0,"-","-"]
["With Legal Agreement",0,"-","-"]
[null,null,null,null,null,null,null,null,null,"OK"]
["All Local Developments",105,null,5.1197278911564625,null,null,null,null,null,"OK","OK",{"$error":"#VALUE!"}]
["Without Legal Agreement",105,1,5.1197278911564625]
["With Legal Agreement",0,0,"-"]
["Local: less than 2 months",101,0.96190476190476193,4.9108910891089108,null,null,null,null,null,"OK","OK","OK"]
["Local: more than 2 months",4,3.8095238095238099E-2,10.392857142857142]
[]
["All Local developments (non-householder)",48,null,5.9880952380952381,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",44,0.91666666666666663,5.587662337662338]
["Local: more than 2 months",4,8.3333333333333329E-2,10.392857142857142]
[]
["Householder developments",57,null,4.3884711779448624,null,null,null,null,null,"OK","OK",{"$error":"#VALUE!"}]
["Local: less than 2 months",57,1,4.3884711779448624]
["Local: more than 2 months",0,0,"-"]
[]
["Housing Developments - Major",0,null,"-"]
[]
["Housing Developments - Local",20,null,6.3928571428571432,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",18,0.9,6.0158730158730167]
["Local: more than 2 months",2,0.1,9.7857142857142865]
[]
["Business & Industry - Major",0,null,"-"]
[]
["Business & Industry - Local",3,null,6.6190476190476195,null,null,null,null,null,"OK","OK",{"$error":"#VALUE!"}]
["Local: less than 2 months",3,1,6.6190476190476195]
["Local: more than 2 months",0,0,"-"]
[]
["Other developments - Major",0,null,"-",null,null,null,null,null," "]
[]
["Other developments - Local",23,null,5.4596273291925472,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",21,0.91304347826086951,4.9319727891156466]
["Local: more than 2 months",2,8.6956521739130432E-2,11]
[]
["EIA Developments",0,null,"-"]
["Other Consents",22,null,4.9805194805194812]
[]
["Decision Making: Applications subject to"]
["Planning/Legal Agreements",0,null,"-"]
["Local Reviews",2,null,8.2857142857142865,null,null,null,null,null,"Check local review totals"]
[null,null,null,null,null,null,null,null,null,"OK"]
["Decision Making: Local Reviews and Appeals"]
[]
[null,"Total number of decisions","Original decision upheld (%)"]
["Local Reviews",2,0.5]
["Appeals to Scottish Ministers2",0,"-"]
[]
["Enforcement Activity"]
[]
[null,"Number"]
["Cases Taken Up",19]
["Notices Served",3]
["Reports to Procurator Fiscal",0]
["Prosecutions",0]
["Number of breaches resolved",48]
["Approved and Delegated"]
[]
["Percentage Approved",0.96551724137931039,null,null,null,null,null,null,"Approved",112,116,"Total Applications less N17"]
["Percentage Delegated",0.96850393700787396,null,null,null,null,null,null,"Delegated",123,127,"Total Applications"]
[null,null,null,null,null,null,null,null,null,null,135,"applications received"]
["1. For a full description of the categories in this analysis please see NOTES page."]
["2. Cases where the decision was recalled and made by Ministers are not included in these figures."]
["3. Time has been removed from the decision time for 6 applications where delays were outwith the control of the local authority."]

{"sheet":"North Lanarkshire","index":32,"n_rows":77,"n_cols":13,"rows_kept":77,"cut":false,"hidden":false,"merged":[[2,5,2,7],[61,0,61,3],[76,0,77,3],[0,8,0,12]]}
["Planning Authority Performance Statistics1,3",null,null,"North Lanarkshire",null,null,null,null,"For Scottish Government Use during analysis\nPlease do not delete or move these columns"]
[null,null,null,"2018/19 Q3",null,null,null,null,null,"Check total number of applications"]
[null,null,null,"All Applications excluding Legacy Cases",null,null,null,null,null,227,"total apps",null,"OK"]
[null,null,null,null,null,null,null,null,null," "]
["Processing Agreements","Total Number of Decisions","% Within Agreed Timescales"]
["TOTAL",30,0.16666666666666666]
["Major Applications",3,0.33333333333333331]
["Local Applications",24,0.16666666666666666]
["EIA  Applications",0,"-"]
["Other Applications",3,0]
["Applications with processing agreements are not included in the following figures."]
[null,"Total Number of Decisions","Proportion of Decisions","Average Time (Weeks)",null,null,null,null,null,"check sums to total"]
["All Major Developments",3,null,28.428571428571427,null,null,null,null,null,"OK","OK",{"$error":"#VALUE!"}]
["Without Legal Agreement",3,1,28.428571428571427]
["With Legal Agreement",0,0,"-"]
[null,null,null,null,null,null,null,null,null,"OK"]
["All Local Developments",156,null,8.4432234432234434,null,null,null,null,null,"OK","OK","OK"]
["Without Legal Agreement",155,0.99358974358974361,7.5944700460829493]
["With Legal Agreement",1,6.41025641025641E-3,140]
["Local: less than 2 months",115,0.73717948717948723,6.4583850931677018,null,null,null,null,null,"OK","OK","OK"]
["Local: more than 2 months",41,0.26282051282051283,14.010452961672474]
[]
["All Local developments (non-householder)",60,null,10.473809523809523,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",39,0.65,6.3699633699633704]
["Local: more than 2 months",21,0.35,18.095238095238095]
[]
["Householder developments",96,null,7.1741071428571432,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",76,0.79166666666666663,6.503759398496241]
["Local: more than 2 months",20,0.20833333333333334,9.7214285714285715]
[]
["Housing Developments - Major",2,null,33.857142857142854]
[]
["Housing Developments - Local",13,null,21.219780219780223,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",4,0.30769230769230771,7.3214285714285712]
["Local: more than 2 months",9,0.69230769230769229,27.396825396825395]
[]
["Business & Industry - Major",0,null,"-"]
[]
["Business & Industry - Local",19,null,8.3082706766917287,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",13,0.68421052631578949,6.9010989010989006]
["Local: more than 2 months",6,0.31578947368421051,11.357142857142858]
[]
["Other developments - Major",1,null,17.571428571428573,null,null,null,null,null," "]
[]
["Other developments - Local",27,null,7.0158730158730167,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",21,0.77777777777777779,5.9115646258503398]
["Local: more than 2 months",6,0.22222222222222221,10.880952380952381]
[]
["EIA Developments",0,null,"-"]
["Other Consents",38,null,5.484962406015037]
[]
["Decision Making: Applications subject to"]
["Planning/Legal Agreements",1,null,140]
["Local Reviews",5,null,8.1714285714285726,null,null,null,null,null,"Check local review totals"]
[null,null,null,null,null,null,null,null,null,"OK"]
["Decision Making: Local Reviews and Appeals"]
[]
[null,"Total number of decisions","Original decision upheld (%)"]
["Local Reviews",5,0.6]
["Appeals to Scottish Ministers2",3,1]
[]
["Enforcement Activity"]
[]
[null,"Number"]
["Cases Taken Up",9]
["Notices Served",0]
["Reports to Procurator Fiscal",0]
["Prosecutions",0]
["Number of breaches resolved",32]
["Approved and Delegated"]
[]
["Percentage Approved",0.95121951219512191,null,null,null,null,null,null,"Approved",195,205,"Total Applications less N17"]
["Percentage Delegated",0.95594713656387664,null,null,null,null,null,null,"Delegated",217,227,"Total Applications"]
[null,null,null,null,null,null,null,null,null,null,275,"applications received"]
["1. For a full description of the categories in this analysis please see NOTES page."]
["2. Cases where the decision was recalled and made by Ministers are not included in these figures."]
["3. Time has been removed from the decision time for 4 applications where delays were outwith the control of the local authority."]

{"sheet":" Orkney Islands","index":33,"n_rows":77,"n_cols":13,"rows_kept":77,"cut":false,"hidden":false,"merged":[[2,5,2,7],[61,0,61,3],[76,0,77,3],[0,8,0,12]]}
["Planning Authority Performance Statistics1,3",null,null,"Orkney Islands",null,null,null,null,"For Scottish Government Use during analysis\nPlease do not delete or move these columns"]
[null,null,null,"2018/19 Q3",null,null,null,null,null,"Check total number of applications"]
[null,null,null,"All Applications excluding Legacy Cases",null,null,null,null,null,115,"total apps",null,"OK"]
[null,null,null,null,null,null,null,null,null," "]
["Processing Agreements","Total Number of Decisions","% Within Agreed Timescales"]
["TOTAL",0,"-"]
["Major Applications",0,"-"]
["Local Applications",0,"-"]
["EIA  Applications",0,"-"]
["Other Applications",0,"-"]
["Applications with processing agreements are not included in the following figures."]
[null,"Total Number of Decisions","Proportion of Decisions","Average Time (Weeks)",null,null,null,null,null,"check sums to total"]
["All Major Developments",0,null,"-",null,null,null,null,null,"OK",{"$error":"#VALUE!"},{"$error":"#VALUE!"}]
["Without Legal Agreement",0,"-","-"]
["With Legal Agreement",0,"-","-"]
[null,null,null,null,null,null,null,null,null,"OK"]
["All Local Developments",90,null,7.9031746031746035,null,null,null,null,null,"OK","OK","OK"]
["Without Legal Agreement",89,0.98888888888888893,7.8892455858747992]
["With Legal Agreement",1,1.1111111111111112E-2,9.1428571428571423]
["Local: less than 2 months",64,0.71111111111111114,6.4508928571428568,null,null,null,null,null,"OK","OK","OK"]
["Local: more than 2 months",26,0.28888888888888886,11.478021978021976]
[]
["All Local developments (non-householder)",67,null,8.3795309168443488,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",45,0.67164179104477617,6.6793650793650787]
["Local: more than 2 months",22,0.32835820895522388,11.857142857142858]
[]
["Householder developments",23,null,6.5155279503105588,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",19,0.82608695652173914,5.9097744360902258]
["Local: more than 2 months",4,0.17391304347826086,9.3928571428571423]
[]
["Housing Developments - Major",0,null,"-"]
[]
["Housing Developments - Local",31,null,7.9308755760368665,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",23,0.74193548387096775,6.7142857142857144]
["Local: more than 2 months",8,0.25806451612903225,11.428571428571429]
[]
["Business & Industry - Major",0,null,"-"]
[]
["Business & Industry - Local",22,null,7.7532467532467537,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",14,0.63636363636363635,6.3469387755102042]
["Local: more than 2 months",8,0.36363636363636365,10.214285714285714]
[]
["Other developments - Major",0,null,"-",null,null,null,null,null," "]
[]
["Other developments - Local",6,null,13.166666666666668,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",5,0.83333333333333337,7.6000000000000005]
["Local: more than 2 months",1,0.16666666666666666,41]
[]
["EIA Developments",0,null,"-"]
["Other Consents",25,null,5.4685714285714289]
[]
["Decision Making: Applications subject to"]
["Planning/Legal Agreements",1,null,9.1428571428571423]
["Local Reviews",2,null,16.714285714285715,null,null,null,null,null,"Check local review totals"]
[null,null,null,null,null,null,null,null,null,"OK"]
["Decision Making: Local Reviews and Appeals"]
[]
[null,"Total number of decisions","Original decision upheld (%)"]
["Local Reviews",2,0.5]
["Appeals to Scottish Ministers2",0,"-"]
[]
["Enforcement Activity"]
[]
[null,"Number"]
["Cases Taken Up",0]
["Notices Served",0]
["Reports to Procurator Fiscal",0]
["Prosecutions",0]
["Number of breaches resolved",0]
["Approved and Delegated"]
[]
["Percentage Approved",0.93203883495145634,null,null,null,null,null,null,"Approved",96,103,"Total Applications less N17"]
["Percentage Delegated",0.9826086956521739,null,null,null,null,null,null,"Delegated",113,115,"Total Applications"]
[null,null,null,null,null,null,null,null,null,null,133,"applications received"]
["1. For a full description of the categories in this analysis please see NOTES page."]
["2. Cases where the decision was recalled and made by Ministers are not included in these figures."]
["3. Time has been removed from the decision time for 21 applications where delays were outwith the control of the local authority."]

{"sheet":"Perth and Kinross","index":34,"n_rows":77,"n_cols":14,"rows_kept":77,"cut":false,"hidden":false,"merged":[[79,0,80,3],[76,0,77,3],[2,5,2,7],[0,8,0,12],[61,0,61,3]]}
["Planning Authority Performance Statistics1,3",null,null,"Perth and Kinross",null,null,null,null,"For Scottish Government Use during analysis\nPlease do not delete or move these columns"]
[null,null,null,"2018/19 Q3",null,null,null,null,null,"Check total number of applications"]
[null,null,null,"All Applications excluding Legacy Cases",null,null,null,null,null,423,"total apps",null,"OK"]
[null,null,null,null,null,null,null,null,null," "]
["Processing Agreements","Total Number of Decisions","% Within Agreed Timescales"]
["TOTAL",8,0.75]
["Major Applications",1,1]
["Local Applications",4,1]
["EIA  Applications",0,"-"]
["Other Applications",3,0.33333333333333331]
["Applications with processing agreements are not included in the following figures."]
[null,"Total Number of Decisions","Proportion of Decisions","Average Time (Weeks)",null,null,null,null,null,"check sums to total"]
["All Major Developments",4,null,32.5,null,null,null,null,null,"OK","OK","OK"]
["Without Legal Agreement",3,0.75,16.476190476190474]
["With Legal Agreement",1,0.25,80.571428571428569]
[null,null,null,null,null,null,null,null,null,"OK"]
["All Local Developments",299,null,7.2689918776875304,null,null,null,null,null,"OK","OK","OK"]
["Without Legal Agreement",296,0.98996655518394649,7.1505791505791505]
["With Legal Agreement",3,1.0033444816053512E-2,18.952380952380953]
["Local: less than 2 months",241,0.80602006688963213,6.0717249555423836,null,null,null,null,null,"OK","OK","OK"]
["Local: more than 2 months",58,0.1939799331103679,12.24384236453202]
[]
["All Local developments (non-householder)",160,null,7.6401785714285717,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",124,0.77500000000000002,5.9654377880184333]
["Local: more than 2 months",36,0.22500000000000001,13.40873015873016]
[]
["Householder developments",139,null,6.8417266187050361,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",117,0.84172661870503596,6.1843711843711846]
["Local: more than 2 months",22,0.15827338129496402,10.337662337662337]
[]
["Housing Developments - Major",1,null,8.7142857142857135]
[]
["Housing Developments - Local",69,null,7.9648033126293996,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",49,0.71014492753623193,6.1341107871720117]
["Local: more than 2 months",20,0.28985507246376813,12.450000000000001]
[]
["Business & Industry - Major",1,null,1.5714285714285714]
[]
["Business & Industry - Local",11,null,7.1688311688311686,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",8,0.72727272727272729,5.5535714285714288]
["Local: more than 2 months",3,0.27272727272727271,11.476190476190476]
[]
["Other developments - Major",1,null,80.571428571428569,null,null,null,null,null," "]
[]
["Other developments - Local",75,null,7.0266666666666664,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",64,0.85333333333333339,5.9308035714285712]
["Local: more than 2 months",11,0.14666666666666667,13.402597402597403]
[]
["EIA Developments",0,null,"-"]
["Other Consents",112,null,5.904336734693878]
[]
["Decision Making: Applications subject to"]
["Planning/Legal Agreements",4,null,34.357142857142854,null,null,null,null,null,null,null,null,null,52]
["Local Reviews",18,null,19.357142857142858,null,null,null,null,null,"Check local review totals",null,null,null,49]
[null,null,null,null,null,null,null,null,null,"OK","OK"]
["Decision Making: Local Reviews and Appeals"]
[]
[null,"Total number of decisions","Original decision upheld (%)"]
["Local Reviews",18,0.78]
["Appeals to Scottish Ministers2",1,1]
[]
["Enforcement Activity"]
[]
[null,"Number"]
["Cases Taken Up",78]
["Notices Served",11]
["Reports to Procurator Fiscal",1]
["Prosecutions",0]
["Number of breaches resolved",194]
["Approved and Delegated"]
[]
["Percentage Approved",0.88888888888888884,null,null,null,null,null,null,"Approved",344,387,"Total Applications less N17"]
["Percentage Delegated",0.97399527186761226,null,null,null,null,null,null,"Delegated",412,423,"Total Applications"]
[null,null,null,null,null,null,null,null,null,null,447,"applications received"]
["1. For a full description of the categories in this analysis please see NOTES page."]
["2. Cases where the decision was recalled and made by Ministers are not included in these figures."]
["3. Time has been removed from the decision time for 15 applications where delays were outwith the control of the local authority."]

{"sheet":"Renfrewshire","index":35,"n_rows":77,"n_cols":13,"rows_kept":77,"cut":false,"hidden":false,"merged":[[61,0,61,3],[76,0,77,3],[2,5,2,7],[0,8,0,12]]}
["Planning Authority Performance Statistics1,3",null,null,"Renfrewshire",null,null,null,null,"For Scottish Government Use during analysis\nPlease do not delete or move these columns"]
[null,null,null,"2018/19 Q3",null,null,null,null,null,"Check total number of applications"]
[null,null,null,"All Applications excluding Legacy Cases",null,null,null,null,null,160,"total apps",null,"OK"]
[null,null,null,null,null,null,null,null,null," "]
["Processing Agreements","Total Number of Decisions","% Within Agreed Timescales"]
["TOTAL",0,"-"]
["Major Applications",0,"-"]
["Local Applications",0,"-"]
["EIA  Applications",0,"-"]
["Other Applications",0,"-"]
["Applications with processing agreements are not included in the following figures."]
[null,"Total Number of Decisions","Proportion of Decisions","Average Time (Weeks)",null,null,null,null,null,"check sums to total"]
["All Major Developments",3,null,54.571428571428569,null,null,null,null,null,"OK","OK","OK"]
["Without Legal Agreement",1,0.33333333333333331,22.571428571428573]
["With Legal Agreement",2,0.66666666666666663,70.571428571428569]
[null,null,null,null,null,null,null,null,null,"OK"]
["All Local Developments",116,null,7.1773399014778319,null,null,null,null,null,"OK","OK","OK"]
["Without Legal Agreement",115,0.99137931034482762,6.6844720496894405]
["With Legal Agreement",1,8.6206896551724137E-3,63.857142857142854]
["Local: less than 2 months",103,0.88793103448275867,6.2371705963938968,null,null,null,null,null,"OK","OK","OK"]
["Local: more than 2 months",13,0.11206896551724138,14.626373626373626]
[]
["All Local developments (non-householder)",47,null,7.9939209726443767,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",41,0.87234042553191493,6.2299651567944254]
["Local: more than 2 months",6,0.1276595744680851,20.047619047619047]
[]
["Householder developments",69,null,6.6211180124223601,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",62,0.89855072463768115,6.241935483870968]
["Local: more than 2 months",7,0.10144927536231885,9.979591836734695]
[]
["Housing Developments - Major",2,null,70.571428571428569]
[]
["Housing Developments - Local",11,null,7.116883116883117,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",9,0.81818181818181823,6.4761904761904763]
["Local: more than 2 months",2,0.18181818181818182,10]
[]
["Business & Industry - Major",0,null,"-"]
[]
["Business & Industry - Local",5,null,7.8,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",4,0.8,6.6071428571428568]
["Local: more than 2 months",1,0.2,12.571428571428571]
[]
["Other developments - Major",1,null,22.571428571428573,null,null,null,null,null," "]
[]
["Other developments - Local",28,null,8.2295918367346932,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",26,0.9285714285714286,5.9945054945054945]
["Local: more than 2 months",2,7.1428571428571425E-2,37.285714285714285]
[]
["EIA Developments",0,null,"-"]
["Other Consents",41,null,6.1010452961672481]
[]
["Decision Making: Applications subject to"]
["Planning/Legal Agreements",3,null,68.333333333333329]
["Local Reviews",1,null,10.142857142857142,null,null,null,null,null,"Check local review totals"]
[null,null,null,null,null,null,null,null,null,"OK"]
["Decision Making: Local Reviews and Appeals"]
[]
[null,"Total number of decisions","Original decision upheld (%)"]
["Local Reviews",1,1]
["Appeals to Scottish Ministers2",0,"-"]
[]
["Enforcement Activity"]
[]
[null,"Number"]
["Cases Taken Up",0]
["Notices Served",3]
["Reports to Procurator Fiscal",0]
["Prosecutions",0]
["Number of breaches resolved",0]
["Approved and Delegated"]
[]
["Percentage Approved",0.98,null,null,null,null,null,null,"Approved",147,150,"Total Applications less N17"]
["Percentage Delegated",0.97499999999999998,null,null,null,null,null,null,"Delegated",156,160,"Total Applications"]
[null,null,null,null,null,null,null,null,null,null,114,"applications received"]
["1. For a full description of the categories in this analysis please see NOTES page."]
["2. Cases where the decision was recalled and made by Ministers are not included in these figures."]
["3. Time has been removed from the decision time for 18 applications where delays were outwith the control of the local authority."]

{"sheet":"Scottish Borders","index":36,"n_rows":77,"n_cols":13,"rows_kept":77,"cut":false,"hidden":false,"merged":[[79,0,80,3],[61,0,61,3],[2,5,2,7],[0,8,0,12],[76,0,77,3]]}
["Planning Authority Performance Statistics1,3",null,null,"Scottish Borders",null,null,null,null,"For Scottish Government Use during analysis\nPlease do not delete or move these columns"]
[null,null,null,"2018/19 Q3",null,null,null,null,null,"Check total number of applications"]
[null,null,null,"All Applications excluding Legacy Cases",null,null,null,null,null,296,"total apps",null,"OK"]
[null,null,null,null,null,null,null,null,null," "]
["Processing Agreements","Total Number of Decisions","% Within Agreed Timescales"]
["TOTAL",104,0.92307692307692313]
["Major Applications",0,"-"]
["Local Applications",95,0.91578947368421049]
["EIA  Applications",0,"-"]
["Other Applications",9,1]
["Applications with processing agreements are not included in the following figures."]
[null,"Total Number of Decisions","Proportion of Decisions","Average Time (Weeks)",null,null,null,null,null,"check sums to total"]
["All Major Developments",1,null,12.428571428571429,null,null,null,null,null,"OK","OK",{"$error":"#VALUE!"}]
["Without Legal Agreement",1,1,12.428571428571429]
["With Legal Agreement",0,0,"-"]
[null,null,null,null,null,null,null,null,null,"OK"]
["All Local Developments",147,null,7.185617103984451,null,null,null,null,null,"OK","OK",{"$error":"#VALUE!"}]
["Without Legal Agreement",147,1,7.185617103984451]
["With Legal Agreement",0,0,"-"]
["Local: less than 2 months",118,0.80272108843537415,6.2312348668280872,null,null,null,null,null,"OK","OK","OK"]
["Local: more than 2 months",29,0.19727891156462585,11.068965517241379]
[]
["All Local developments (non-householder)",59,null,7.9661016949152543,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",43,0.72881355932203384,6.4784053156146175]
["Local: more than 2 months",16,0.2711864406779661,11.964285714285714]
[]
["Householder developments",88,null,6.662337662337662,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",75,0.85227272727272729,6.0895238095238096]
["Local: more than 2 months",13,0.14772727272727273,9.9670329670329672]
[]
["Housing Developments - Major",0,null,"-"]
[]
["Housing Developments - Local",14,null,9.0612244897959187,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",9,0.6428571428571429,6.8888888888888884]
["Local: more than 2 months",5,0.35714285714285715,12.971428571428572]
[]
["Business & Industry - Major",0,null,"-"]
[]
["Business & Industry - Local",10,null,6.8571428571428568,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",8,0.8,6.3214285714285712]
["Local: more than 2 months",2,0.2,9]
[]
["Other developments - Major",1,null,12.428571428571429,null,null,null,null,null," "]
[]
["Other developments - Local",34,null,7.575630252100841,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",26,0.76470588235294112,6.384615384615385]
["Local: more than 2 months",8,0.23529411764705882,11.446428571428571]
[]
["EIA Developments",0,null,"-"]
["Other Consents",44,null,6.9577922077922079]
[]
["Decision Making: Applications subject to"]
["Planning/Legal Agreements",0,null,"-"]
["Local Reviews",9,null,6.1428571428571432,null,null,null,null,null,"Check local review totals"]
[null,null,null,null,null,null,null,null,null,"OK"]
["Decision Making: Local Reviews and Appeals"]
[]
[null,"Total number of decisions","Original decision upheld (%)"]
["Local Reviews",9,0.44444444444444442]
["Appeals to Scottish Ministers2",4,0.25]
[]
["Enforcement Activity"]
[]
[null,"Number"]
["Cases Taken Up",42]
["Notices Served",4]
["Reports to Procurator Fiscal",0]
["Prosecutions",0]
["Number of breaches resolved",51]
["Approved and Delegated"]
[]
["Percentage Approved",0.93243243243243246,null,null,null,null,null,null,"Approved",276,296,"Total Applications less N17"]
["Percentage Delegated",0.96959459459459463,null,null,null,null,null,null,"Delegated",287,296,"Total Applications"]
[null,null,null,null,null,null,null,null,null,null,321,"applications received"]
["1. For a full description of the categories in this analysis please see NOTES page."]
["2. Cases where the decision was recalled and made by Ministers are not included in these figures."]
["3. Time has been removed from the decision time for 1 applications where delays were outwith the control of the local authority."]

{"sheet":"Shetland Islands","index":37,"n_rows":77,"n_cols":13,"rows_kept":77,"cut":false,"hidden":false,"merged":[[2,5,2,7],[61,0,61,3],[76,0,77,3],[0,8,0,12]]}
["Planning Authority Performance Statistics1,3",null,null,"Shetland Islands",null,null,null,null,"For Scottish Government Use during analysis\nPlease do not delete or move these columns"]
[null,null,null,"2018/19 Q3",null,null,null,null,null,"Check total number of applications"]
[null,null,null,"All Applications excluding Legacy Cases",null,null,null,null,null,67,"total apps",null,"OK"]
[null,null,null,null,null,null,null,null,null," "]
["Processing Agreements","Total Number of Decisions","% Within Agreed Timescales"]
["TOTAL",0,"-"]
["Major Applications",0,"-"]
["Local Applications",0,"-"]
["EIA  Applications",0,"-"]
["Other Applications",0,"-"]
["Applications with processing agreements are not included in the following figures."]
[null,"Total Number of Decisions","Proportion of Decisions","Average Time (Weeks)",null,null,null,null,null,"check sums to total"]
["All Major Developments",1,null,16.857142857142858,null,null,null,null,null,"OK","OK",{"$error":"#VALUE!"}]
["Without Legal Agreement",1,1,16.857142857142858]
["With Legal Agreement",0,0,"-"]
[null,null,null,null,null,null,null,null,null,"OK"]
["All Local Developments",55,null,15.737662337662337,null,null,null,null,null,"OK","OK",{"$error":"#VALUE!"}]
["Without Legal Agreement",55,1,15.737662337662337]
["With Legal Agreement",0,0,"-"]
["Local: less than 2 months",4,7.2727272727272724E-2,7.3571428571428568,null,null,null,null,null,"OK","OK","OK"]
["Local: more than 2 months",51,0.92727272727272725,16.394957983193276]
[]
["All Local developments (non-householder)",43,null,16.033222591362126,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",3,6.9767441860465115E-2,7]
["Local: more than 2 months",40,0.93023255813953487,16.710714285714285]
[]
["Householder developments",12,null,14.678571428571429,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",1,8.3333333333333329E-2,8.4285714285714288]
["Local: more than 2 months",11,0.91666666666666663,15.246753246753247]
[]
["Housing Developments - Major",0,null,"-"]
[]
["Housing Developments - Local",18,null,17.738095238095237,null,null,null,null,null,"OK","OK",{"$error":"#VALUE!"}]
["Local: less than 2 months",0,0,"-"]
["Local: more than 2 months",18,1,17.738095238095237]
[]
["Business & Industry - Major",0,null,"-"]
[]
["Business & Industry - Local",7,null,15.938775510204081,null,null,null,null,null,"OK","OK",{"$error":"#VALUE!"}]
["Local: less than 2 months",0,0,"-"]
["Local: more than 2 months",7,1,15.938775510204081]
[]
["Other developments - Major",0,null,"-",null,null,null,null,null," "]
[]
["Other developments - Local",10,null,14.37142857142857,null,null,null,null,null,"OK","OK",{"$error":"#VALUE!"}]
["Local: less than 2 months",0,0,"-"]
["Local: more than 2 months",10,1,14.37142857142857]
[]
["EIA Developments",2,null,19.428571428571427]
["Other Consents",9,null,5.9841269841269833]
[]
["Decision Making: Applications subject to"]
["Planning/Legal Agreements",0,null,"-"]
["Local Reviews",0,null,"-",null,null,null,null,null,"Check local review totals"]
[null,null,null,null,null,null,null,null,null,"OK"]
["Decision Making: Local Reviews and Appeals"]
[]
[null,"Total number of decisions","Original decision upheld (%)"]
["Local Reviews",0,"-"]
["Appeals to Scottish Ministers2",0,"-"]
[]
["Enforcement Activity"]
[]
[null,"Number"]
["Cases Taken Up",0]
["Notices Served",0]
["Reports to Procurator Fiscal",0]
["Prosecutions",0]
["Number of breaches resolved",14]
["Approved and Delegated"]
[]
["Percentage Approved",1,null,null,null,null,null,null,"Approved",61,61,"Total Applications less N17"]
["Percentage Delegated",0.9850746268656716,null,null,null,null,null,null,"Delegated",66,67,"Total Applications"]
[null,null,null,null,null,null,null,null,null,null,71,"applications received"]
["1. For a full description of the categories in this analysis please see NOTES page."]
["2. Cases where the decision was recalled and made by Ministers are not included in these figures."]
["3. Time has been removed from the decision time for 10 applications where delays were outwith the control of the local authority."]

{"sheet":"South Ayrshire","index":38,"n_rows":77,"n_cols":13,"rows_kept":77,"cut":false,"hidden":false,"merged":[[61,0,61,3],[2,5,2,7],[0,8,0,12]]}
["Planning Authority Performance Statistics1,3",null,null,"South Ayrshire",null,null,null,null,"For Scottish Government Use during analysis\nPlease do not delete or move these columns"]
[null,null,null,"2018/19 Q3",null,null,null,null,null,"Check total number of applications"]
[null,null,null,"All Applications excluding Legacy Cases",null,null,null,null,null,221,"total apps",null,"OK"]
[null,null,null,null,null,null,null,null,null," "]
["Processing Agreements","Total Number of Decisions","% Within Agreed Timescales"]
["TOTAL",5,1]
["Major Applications",2,1]
["Local Applications",3,1]
["EIA  Applications",0,"-"]
["Other Applications",0,"-"]
["Applications with processing agreements are not included in the following figures."]
[null,"Total Number of Decisions","Proportion of Decisions","Average Time (Weeks)",null,null,null,null,null,"check sums to total"]
["All Major Developments",0,null,"-",null,null,null,null,null,"OK",{"$error":"#VALUE!"},{"$error":"#VALUE!"}]
["Without Legal Agreement",0,"-","-"]
["With Legal Agreement",0,"-","-"]
[null,null,null,null,null,null,null,null,null,"OK"]
["All Local Developments",172,null,6.4385382059800662,null,null,null,null,null,"OK","OK",{"$error":"#VALUE!"}]
["Without Legal Agreement",172,1,6.4385382059800662]
["With Legal Agreement",0,0,"-"]
["Local: less than 2 months",160,0.93023255813953487,6.1437499999999998,null,null,null,null,null,"OK","OK","OK"]
["Local: more than 2 months",12,6.9767441860465115E-2,10.369047619047619]
[]
["All Local developments (non-householder)",95,null,6.5308270676691729,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",84,0.88421052631578945,6.0085034013605441]
["Local: more than 2 months",11,0.11578947368421053,10.519480519480521]
[]
["Householder developments",77,null,6.3246753246753249,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",76,0.98701298701298701,6.2932330827067675]
["Local: more than 2 months",1,1.2987012987012988E-2,8.7142857142857135]
[]
["Housing Developments - Major",0,null,"-"]
[]
["Housing Developments - Local",41,null,6.3484320557491287,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",38,0.92682926829268297,6.041353383458647]
["Local: more than 2 months",3,7.3170731707317069E-2,10.238095238095239]
[]
["Business & Industry - Major",0,null,"-"]
[]
["Business & Industry - Local",10,null,8.1285714285714281,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",7,0.7,6.3265306122448974]
["Local: more than 2 months",3,0.3,12.333333333333332]
[]
["Other developments - Major",0,null,"-",null,null,null,null,null," "]
[]
["Other developments - Local",42,null,6.27891156462585,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",37,0.88095238095238093,5.8301158301158305]
["Local: more than 2 months",5,0.11904761904761904,9.6]
[]
["EIA Developments",0,null,"-"]
["Other Consents",44,null,4.5259740259740262]
[]
["Decision Making: Applications subject to"]
["Planning/Legal Agreements",0,null,"-"]
["Local Reviews",6,null,21.666666666666664,null,null,null,null,null,"Check local review totals"]
[null,null,null,null,null,null,null,null,null,"OK"]
["Decision Making: Local Reviews and Appeals"]
[]
[null,"Total number of decisions","Original decision upheld (%)"]
["Local Reviews",6,0.5]
["Appeals to Scottish Ministers2",3,0.33300000000000002]
[]
["Enforcement Activity"]
[]
[null,"Number"]
["Cases Taken Up",50]
["Notices Served",3]
["Reports to Procurator Fiscal",0]
["Prosecutions",0]
["Number of breaches resolved",46]
["Approved and Delegated"]
[]
["Percentage Approved",0.93069306930693074,null,null,null,null,null,null,"Approved",188,202,"Total Applications less N17"]
["Percentage Delegated",0.95927601809954754,null,null,null,null,null,null,"Delegated",212,221,"Total Applications"]
[null,null,null,null,null,null,null,null,null,null,184,"applications received"]
["1. For a full description of the categories in this analysis please see NOTES page."]
["2. Cases where the decision was recalled and made by Ministers are not included in these figures."]
["3. Time has not been removed from the decision time for any applications."]

{"sheet":"South Lanarkshire","index":39,"n_rows":77,"n_cols":13,"rows_kept":77,"cut":false,"hidden":false,"merged":[[61,0,61,3],[76,0,77,3],[2,5,2,7],[0,8,0,12]]}
["Planning Authority Performance Statistics1,3",null,null,"South Lanarkshire",null,null,null,null,"For Scottish Government Use during analysis\nPlease do not delete or move these columns"]
[null,null,null,"2018/19 Q3",null,null,null,null,null,"Check total number of applications"]
[null,null,null,"All Applications excluding Legacy Cases",null,null,null,null,null,352,"total apps",null,"OK"]
[null,null,null,null,null,null,null,null,null," "]
["Processing Agreements","Total Number of Decisions","% Within Agreed Timescales"]
["TOTAL",2,0]
["Major Applications",1,0]
["Local Applications",1,0]
["EIA  Applications",0,"-"]
["Other Applications",0,"-"]
["Applications with processing agreements are not included in the following figures."]
[null,"Total Number of Decisions","Proportion of Decisions","Average Time (Weeks)",null,null,null,null,null,"check sums to total"]
["All Major Developments",3,null,49.571428571428569,null,null,null,null,null,"OK","OK","OK"]
["Without Legal Agreement",1,0.33333333333333331,12]
["With Legal Agreement",2,0.66666666666666663,68.357142857142861]
[null,null,null,null,null,null,null,null,null,"OK"]
["All Local Developments",305,null,10.075409836065575,null,null,null,null,null,"OK","OK","OK"]
["Without Legal Agreement",304,0.99672131147540988,10.090695488721805]
["With Legal Agreement",1,3.2786885245901639E-3,5.4285714285714288]
["Local: less than 2 months",191,0.6262295081967213,5.5003739715781608,null,null,null,null,null,"OK","OK","OK"]
["Local: more than 2 months",114,0.3737704918032787,17.7406015037594]
[]
["All Local developments (non-householder)",138,null,13.550724637681158,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",55,0.39855072463768115,6.5428571428571427]
["Local: more than 2 months",83,0.60144927536231885,18.194492254733216]
[]
["Householder developments",167,null,7.2035928143712571,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",136,0.81437125748502992,5.0787815126050422]
["Local: more than 2 months",31,0.18562874251497005,16.525345622119815]
[]
["Housing Developments - Major",3,null,49.571428571428569]
[]
["Housing Developments - Local",59,null,14.508474576271187,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",23,0.38983050847457629,6.7204968944099379]
["Local: more than 2 months",36,0.61016949152542377,19.484126984126984]
[]
["Business & Industry - Major",0,null,"-"]
[]
["Business & Industry - Local",14,null,10.663265306122449,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",7,0.5,6.2244897959183669]
["Local: more than 2 months",7,0.5,15.102040816326531]
[]
["Other developments - Major",0,null,"-",null,null,null,null,null," "]
[]
["Other developments - Local",62,null,13.262672811059909,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",24,0.38709677419354838,6.4226190476190483]
["Local: more than 2 months",38,0.61290322580645162,17.582706766917294]
[]
["EIA Developments",0,null,"-"]
["Other Consents",42,null,10.295918367346939]
[]
["Decision Making: Applications subject to"]
["Planning/Legal Agreements",3,null,47.380952380952387]
["Local Reviews",0,null,"-",null,null,null,null,null,"Check local review totals"]
[null,null,null,null,null,null,null,null,null,"OK"]
["Decision Making: Local Reviews and Appeals"]
[]
[null,"Total number of decisions","Original decision upheld (%)"]
["Local Reviews",0,"-"]
["Appeals to Scottish Ministers2",2,0.5]
[]
["Enforcement Activity"]
[]
[null,"Number"]
["Cases Taken Up",10]
["Notices Served",2]
["Reports to Procurator Fiscal",0]
["Prosecutions",0]
["Number of breaches resolved",9]
["Approved and Delegated"]
[]
["Percentage Approved",0.98245614035087714,null,null,null,null,null,null,"Approved",336,342,"Total Applications less N17"]
["Percentage Delegated",0.95454545454545459,null,null,null,null,null,null,"Delegated",336,352,"Total Applications"]
[null,null,null,null,null,null,null,null,null,null,372,"applications received"]
["1. For a full description of the categories in this analysis please see NOTES page."]
["2. Cases where the decision was recalled and made by Ministers are not included in these figures."]
["3. Time has been removed from the decision time for 8 applications where delays were outwith the control of the local authority."]

{"sheet":"Stirling","index":40,"n_rows":77,"n_cols":13,"rows_kept":77,"cut":false,"hidden":false,"merged":[[79,0,80,3],[61,0,61,3],[76,0,77,3],[2,5,2,7],[0,8,0,12]]}
["Planning Authority Performance Statistics1,3",null,null,"Stirling",null,null,null,null,"For Scottish Government Use during analysis\nPlease do not delete or move these columns"]
[null,null,null,"2018/19 Q3",null,null,null,null,null,"Check total number of applications"]
[null,null,null,"All Applications excluding Legacy Cases",null,null,null,null,null,{"$f":"'[1]Results Q3'!E253","v":197},"total apps",null,{"$f":"IF(ROUND(B6+B13+B17+B49+B50,6)=ROUND(J3,6),\"OK\",\"error\")","v":"OK"}]
[null,null,null,null,null,null,null,null,null," "]
["Processing Agreements","Total Number of Decisions","% Within Agreed Timescales"]
["TOTAL",{"$f":"'[1]Results Q3'!D20","v":1},{"$f":"IF(B6=0,\"-\",'[1]Results Q3'!E20)","v":1}]
["Major Applications",{"$f":"'[1]Results Q3'!D21","v":1},{"$f":"IF(B7=0,\"-\",'[1]Results Q3'!E21)","v":1}]
["Local Applications",{"$f":"'[1]Results Q3'!D22","v":0},{"$f":"IF(B8=0,\"-\",'[1]Results Q3'!E22)","v":"-"}]
["EIA  Applications",{"$f":"'[1]Results Q3'!D23","v":0},{"$f":"IF(B9=0,\"-\",'[1]Results Q3'!E23)","v":"-"}]
["Other Applications",{"$f":"'[1]Results Q3'!D24","v":0},{"$f":"IF(B10=0,\"-\",'[1]Results Q3'!E24)","v":"-"}]
["Applications with processing agreements are not included in the following figures."]
[null,"Total Number of Decisions","Proportion of Decisions","Average Time (Weeks)",null,null,null,null,null,"check sums to total"]
["All Major Developments",{"$f":"'[1]Results Q3'!D40","v":0},null,{"$f":"IF(B13=0,\"-\",'[1]Results Q3'!E40)","v":"-"},null,null,null,null,null,{"$f":"IF(ROUND((B15+B14),6)=ROUND(B13,6), \"OK\",\"ERROR\")","v":"OK"},{"$f":"IF(C14+C15=1,\"OK\",\"error\")","v":{"$error":"#VALUE!"}},{"$f":"IF(ROUND(C14*D14+C15*D15,6)=ROUND(D13,6),\"OK\",\"ERROR\")","v":{"$error":"#VALUE!"}}]
["Without Legal Agreement",{"$f":"'[1]Results Q3'!D41","v":0},{"$f":"IF($B$13=0,\"-\",B14/$B$13)","v":"-"},{"$f":"IF(B14=0,\"-\",'[1]Results Q3'!E41)","v":"-"}]
["With Legal Agreement",{"$f":"'[1]Results Q3'!D42","v":0},{"$f":"IF($B$13=0,\"-\",B15/$B$13)","v":"-"},{"$f":"IF(B15=0,\"-\",'[1]Results Q3'!E42)","v":"-"}]
[null,null,null,null,null,null,null,null,null,{"$f":"IF(ROUND(B23+B27,6)=ROUND(B17,6), \"OK\",\"ERROR\")","v":"OK"}]
["All Local Developments",{"$f":"'[1]Results Q3'!D64","v":159},null,{"$f":"IF(B17=0,\"-\",'[1]Results Q3'!E64)","v":12.090745732255167},null,null,null,null,null,{"$f":"IF(ROUND(B19+B18,6)=ROUND(B17,6), \"OK\",\"ERROR\")","v":"OK"},{"$f":"IF(C18+C19=1,\"OK\",\"error\")","v":"OK"},{"$f":"IF(ROUND(C18*D18+C19*D19,6)=ROUND(D17,6),\"OK\",\"ERROR\")","v":"OK"}]
["Without Legal Agreement",{"$f":"'[1]Results Q3'!D65","v":152},{"$f":"IF($B$17=0,\"-\",B18/$B$17)","v":0.95597484276729561},{"$f":"IF(B18=0,\"-\",'[1]Results Q3'!E65)","v":8.8599624060150379}]
["With Legal Agreement",{"$f":"'[1]Results Q3'!D66","v":7},{"$f":"IF($B$17=0,\"-\",B19/$B$17)","v":4.40251572327044E-2},{"$f":"IF(B19=0,\"-\",'[1]Results Q3'!E66)","v":82.24489795918366}]
["Local: less than 2 months",{"$f":"'[1]Results Q3'!D89","v":109},{"$f":"IF($B$17=0,\"-\",B20/$B$17)","v":0.68553459119496851},{"$f":"IF(B20=0,\"-\",'[1]Results Q3'!E89)","v":5.6684141546526865},null,null,null,null,null,{"$f":"IF(ROUND(B21+B20,6)=ROUND(B17,6), \"OK\",\"ERROR\")","v":"OK"},{"$f":"IF(C20+C21=1,\"OK\",\"error\")","v":"OK"},{"$f":"IF(ROUND(C20*D20+C21*D21,6)=ROUND(D17,6),\"OK\",\"ERROR\")","v":"OK"}]
["Local: more than 2 months",{"$f":"'[1]Results Q3'!D90","v":50},{"$f":"IF($B$17=0,\"-\",B21/$B$17)","v":0.31446540880503143},{"$f":"IF(B21=0,\"-\",'[1]Results Q3'!E90)","v":26.091428571428569}]
[]
["All Local developments (non-householder)",{"$f":"'[1]Results Q3'!D114","v":76},null,{"$f":"IF(B23=0,\"-\",'[1]Results Q3'!E114)","v":18.82706766917293},null,null,null,null,null,{"$f":"IF(ROUND(B25+B24,6)=ROUND(B23,6), \"OK\",\"ERROR\")","v":"OK"},{"$f":"IF(C24+C25=1,\"OK\",\"error\")","v":"OK"},{"$f":"IF(ROUND(C24*D24+C25*D25,6)=ROUND(D23,6),\"OK\",\"ERROR\")","v":"OK"}]
["Local: less than 2 months",{"$f":"'[1]Results Q3'!D115","v":33},{"$f":"IF($B$23=0,\"-\",B24/$B$23)","v":0.43421052631578949},{"$f":"IF(B24=0,\"-\",'[1]Results Q3'!E115)","v":6.6320346320346317}]
["Local: more than 2 months",{"$f":"'[1]Results Q3'!D116","v":43},{"$f":"IF($B$23=0,\"-\",B25/$B$23)","v":0.56578947368421051},{"$f":"IF(B25=0,\"-\",'[1]Results Q3'!E116)","v":28.186046511627904}]
[]
["Householder developments",{"$f":"'[1]Results Q3'!D136","v":83},null,{"$f":"IF(B27=0,\"-\",'[1]Results Q3'!E136)","v":5.9225473321858866},null,null,null,null,null,{"$f":"IF(ROUND(B29+B28,6)=ROUND(B27,6), \"OK\",\"ERROR\")","v":"OK"},{"$f":"IF(C28+C29=1,\"OK\",\"error\")","v":"OK"},{"$f":"IF(ROUND(C28*D28+C29*D29,6)=ROUND(D27,6),\"OK\",\"ERROR\")","v":"OK"}]
["Local: less than 2 months",{"$f":"'[1]Results Q3'!D137","v":76},{"$f":"IF($B$27=0,\"-\",B28/$B$27)","v":0.91566265060240959},{"$f":"IF(B28=0,\"-\",'[1]Results Q3'!E137)","v":5.25}]
["Local: more than 2 months",{"$f":"'[1]Results Q3'!D138","v":7},{"$f":"IF($B$27=0,\"-\",B29/$B$27)","v":8.4337349397590355E-2},{"$f":"IF(B29=0,\"-\",'[1]Results Q3'!E138)","v":13.224489795918368}]
[]
["Housing Developments - Major",{"$f":"'[1]Results Q3'!D160","v":0},null,{"$f":"IF(B31=0,\"-\",'[1]Results Q3'!E160)","v":"-"}]
[]
["Housing Developments - Local",{"$f":"'[1]Results Q3'!D140","v":31},null,{"$f":"IF(B33=0,\"-\",'[1]Results Q3'!E140)","v":31.069124423963132},null,null,null,null,null,{"$f":"IF(ROUND(B35+B34,6)=ROUND(B33,6), \"OK\",\"ERROR\")","v":"OK"},{"$f":"IF(C34+C35=1,\"OK\",\"error\")","v":"OK"},{"$f":"IF(ROUND(C34*D34+C35*D35,6)=ROUND(D33,6),\"OK\",\"ERROR\")","v":"OK"}]
["Local: less than 2 months",{"$f":"'[1]Results Q3'!D141","v":9},{"$f":"IF($B$33=0,\"-\",B34/$B$33)","v":0.29032258064516131},{"$f":"IF(B34=0,\"-\",'[1]Results Q3'!E141)","v":6.9523809523809517}]
["Local: more than 2 months",{"$f":"'[1]Results Q3'!D142","v":22},{"$f":"IF($B$33=0,\"-\",B35/$B$33)","v":0.70967741935483875},{"$f":"IF(B35=0,\"-\",'[1]Results Q3'!E142)","v":40.935064935064936}]
[]
["Business & Industry - Major",{"$f":"'[1]Results Q3'!D161","v":0},null,{"$f":"IF(B37=0,\"-\",'[1]Results Q3'!E161)","v":"-"}]
[]
["Business & Industry - Local",{"$f":"'[1]Results Q3'!D144","v":7},null,{"$f":"IF(B39=0,\"-\",'[1]Results Q3'!E144)","v":13.448979591836734},null,null,null,null,null,{"$f":"IF(ROUND(B41+B40,6)=ROUND(B39,6), \"OK\",\"ERROR\")","v":"OK"},{"$f":"IF(C40+C41=1,\"OK\",\"error\")","v":"OK"},{"$f":"IF(ROUND(C40*D40+C41*D41,6)=ROUND(D39,6),\"OK\",\"ERROR\")","v":"OK"}]
["Local: less than 2 months",{"$f":"'[1]Results Q3'!D145","v":1},{"$f":"IF($B$39=0,\"-\",B40/$B$39)","v":0.14285714285714285},{"$f":"IF(B40=0,\"-\",'[1]Results Q3'!E145)","v":7}]
["Local: more than 2 months",{"$f":"'[1]Results Q3'!D146","v":6},{"$f":"IF($B$39=0,\"-\",B41/$B$39)","v":0.8571428571428571},{"$f":"IF(B41=0,\"-\",'[1]Results Q3'!E146)","v":14.523809523809524}]
[]
["Other developments - Major",{"$f":"'[1]Results Q3'!D162","v":0},null,{"$f":"IF(B43=0,\"-\",'[1]Results Q3'!E162)","v":"-"},null,null,null,null,null," "]
[]
["Other developments - Local",{"$f":"'[1]Results Q3'!D148","v":35},null,{"$f":"IF(B45=0,\"-\",'[1]Results Q3'!E148)","v":10.102040816326531},null,null,null,null,null,{"$f":"IF(ROUND(B47+B46,6)=ROUND(B45,6), \"OK\",\"ERROR\")","v":"OK"},{"$f":"IF(C46+C47=1,\"OK\",\"error\")","v":"OK"},{"$f":"IF(ROUND(C46*D46+C47*D47,6)=ROUND(D45,6),\"OK\",\"ERROR\")","v":"OK"}]
["Local: less than 2 months",{"$f":"'[1]Results Q3'!D149","v":20},{"$f":"IF($B$45=0,\"-\",B46/$B$45)","v":0.5714285714285714},{"$f":"IF(B46=0,\"-\",'[1]Results Q3'!E149)","v":6.4642857142857144}]
["Local: more than 2 months",{"$f":"'[1]Results Q3'!D150","v":15},{"$f":"IF($B$45=0,\"-\",B47/$B$45)","v":0.42857142857142855},{"$f":"IF(B47=0,\"-\",'[1]Results Q3'!E150)","v":14.952380952380953}]
[]
["EIA Developments",{"$f":"'[1]Results Q3'!D175","v":0},null,{"$f":"IF(B49=0,\"-\",'[1]Results Q3'!E175)","v":"-"}]
["Other Consents",{"$f":"'[1]Results Q3'!D187","v":37},null,{"$f":"IF(B50=0,\"-\",'[1]Results Q3'!E187)","v":9.096525096525097}]
[]
["Decision Making: Applications subject to"]
["Planning/Legal Agreements",{"$f":"'[1]Results Q3'!D205","v":7},null,{"$f":"IF(B53=0,\"-\",'[1]Results Q3'!E205)","v":82.24489795918366}]
["Local Reviews",{"$f":"'[1]Template 2-LRB'!B5","v":3},null,{"$f":"IF(B54=0,\"-\",'[1]Template 2-LRB'!F5)","v":17.333333333333332},null,null,null,null,null,"Check local review totals"]
[null,null,null,null,null,null,null,null,null,{"$f":"IF(ROUND(B59,6)=ROUND(B54,6),\"OK\",\"error\")","v":"OK"}]
["Decision Making: Local Reviews and Appeals"]
[]
[null,"Total number of decisions","Original decision upheld (%)"]
["Local Reviews",{"$f":"B54","v":3},{"$f":"'[1]Template 2-LRB'!E5","v":0}]
["Appeals to Scottish Ministers2",2,0]
[]
["Enforcement Activity"]
[]
[null,"Number"]
["Cases Taken Up",{"$f":"'[1]Templates 3 & 4'!B5","v":9}]
["Notices Served",{"$f":"'[1]Templates 3 & 4'!B6","v":1}]
["Reports to Procurator Fiscal",{"$f":"'[1]Templates 3 & 4'!B7","v":0}]
["Prosecutions",{"$f":"'[1]Templates 3 & 4'!B8","v":0}]
["Number of breaches resolved",{"$f":"'[1]Templates 3 & 4'!B9","v":39}]
["Approved and Delegated"]
[]
["Percentage Approved",{"$f":"'[1]Results Q3'!E230","v":0.93650793650793651},null,null,null,null,null,null,"Approved",{"$f":"'[1]Results Q3'!E228","v":177},{"$f":"'[1]Results Q3'!E229","v":189},"Total Applications less N17"]
["Percentage Delegated",{"$f":"'[1]Results Q3'!E254","v":0.96446700507614214},null,null,null,null,null,null,"Delegated",{"$f":"'[1]Results Q3'!E252","v":190},{"$f":"'[1]Results Q3'!E253","v":197},"Total Applications"]
[null,null,null,null,null,null,null,null,null,null,{"$f":"'[1]Templates 3 & 4'!C25","v":203},"applications received"]
["1. For a full description of the categories in this analysis please see NOTES page."]
["2. Cases where the decision was recalled and made by Ministers are not included in these figures."]
["3. Time has been removed from the decision time for 1 application where delays were outwith the control of the local authority."]

{"sheet":"West Dunbartonshire","index":41,"n_rows":77,"n_cols":13,"rows_kept":77,"cut":false,"hidden":false,"merged":[[79,0,80,3],[76,0,77,3],[2,5,2,7],[0,8,0,12],[61,0,61,3]]}
["Planning Authority Performance Statistics1,3",null,null,"West Dunbartonshire",null,null,null,null,"For Scottish Government Use during analysis\nPlease do not delete or move these columns"]
[null,null,null,"2018/19 Q3",null,null,null,null,null,"Check total number of applications"]
[null,null,null,"All Applications excluding Legacy Cases",null,null,null,null,null,58,"total apps",null,"OK"]
[null,null,null,null,null,null,null,null,null," "]
["Processing Agreements","Total Number of Decisions","% Within Agreed Timescales"]
["TOTAL",0,"-"]
["Major Applications",0,"-"]
["Local Applications",0,"-"]
["EIA  Applications",0,"-"]
["Other Applications",0,"-"]
["Applications with processing agreements are not included in the following figures."]
[null,"Total Number of Decisions","Proportion of Decisions","Average Time (Weeks)",null,null,null,null,null,"check sums to total"]
["All Major Developments",3,null,28.333333333333336,null,null,null,null,null,"OK","OK",{"$error":"#VALUE!"}]
["Without Legal Agreement",3,1,28.333333333333336]
["With Legal Agreement",0,0,"-"]
[null,null,null,null,null,null,null,null,null,"OK"]
["All Local Developments",43,null,11.272425249169435,null,null,null,null,null,"OK","OK",{"$error":"#VALUE!"}]
["Without Legal Agreement",43,1,11.272425249169435]
["With Legal Agreement",0,0,"-"]
["Local: less than 2 months",18,0.41860465116279072,7.1666666666666661,null,null,null,null,null,"OK","OK","OK"]
["Local: more than 2 months",25,0.58139534883720934,14.228571428571428]
[]
["All Local developments (non-householder)",14,null,14.744897959183673,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",5,0.35714285714285715,6.8]
["Local: more than 2 months",9,0.6428571428571429,19.158730158730158]
[]
["Householder developments",29,null,9.5960591133004929,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",13,0.44827586206896552,7.3076923076923075]
["Local: more than 2 months",16,0.55172413793103448,11.455357142857142]
[]
["Housing Developments - Major",2,null,22.571428571428573]
[]
["Housing Developments - Local",1,null,17.714285714285715,null,null,null,null,null,"OK","OK",{"$error":"#VALUE!"}]
["Local: less than 2 months",0,0,"-"]
["Local: more than 2 months",1,1,17.714285714285715]
[]
["Business & Industry - Major",0,null,"-"]
[]
["Business & Industry - Local",5,null,8.0285714285714285,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",4,0.8,7.4642857142857144]
["Local: more than 2 months",1,0.2,10.285714285714286]
[]
["Other developments - Major",1,null,39.857142857142854,null,null,null,null,null," "]
[]
["Other developments - Local",8,null,18.571428571428573,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",1,0.125,4.1428571428571432]
["Local: more than 2 months",7,0.875,20.632653061224488]
[]
["EIA Developments",0,null,"-"]
["Other Consents",12,null,11.738095238095239]
[]
["Decision Making: Applications subject to"]
["Planning/Legal Agreements",0,null,"-"]
["Local Reviews",0,null,"-",null,null,null,null,null,"Check local review totals"]
[null,null,null,null,null,null,null,null,null,"OK"]
["Decision Making: Local Reviews and Appeals"]
[]
[null,"Total number of decisions","Original decision upheld (%)"]
["Local Reviews",0,"-"]
["Appeals to Scottish Ministers2",0,"-"]
[]
["Enforcement Activity"]
[]
[null,"Number"]
["Cases Taken Up",13]
["Notices Served",1]
["Reports to Procurator Fiscal",0]
["Prosecutions",0]
["Number of breaches resolved",6]
["Approved and Delegated"]
[]
["Percentage Approved",0.94230769230769229,null,null,null,null,null,null,"Approved",49,52,"Total Applications less N17"]
["Percentage Delegated",0.86206896551724133,null,null,null,null,null,null,"Delegated",50,58,"Total Applications"]
[null,null,null,null,null,null,null,null,null,null,53,"applications received"]
["1. For a full description of the categories in this analysis please see NOTES page."]
["2. Cases where the decision was recalled and made by Ministers are not included in these figures."]
["3. Time has been removed from the decision time for 17 applications where delays were outwith the control of the local authority."]

{"sheet":"West Lothian","index":42,"n_rows":77,"n_cols":13,"rows_kept":77,"cut":false,"hidden":false,"merged":[[76,0,77,3],[2,5,2,7],[0,8,0,12],[61,0,61,3]]}
["Planning Authority Performance Statistics1,3",null,null,"West Lothian",null,null,null,null,"For Scottish Government Use during analysis\nPlease do not delete or move these columns"]
[null,null,null,"2018/19 Q3",null,null,null,null,null,"Check total number of applications"]
[null,null,null,"All Applications excluding Legacy Cases",null,null,null,null,null,199,"total apps",null,"OK"]
[null,null,null,null,null,null,null,null,null," "]
["Processing Agreements","Total Number of Decisions","% Within Agreed Timescales"]
["TOTAL",3,1]
["Major Applications",0,"-"]
["Local Applications",3,1]
["EIA  Applications",0,"-"]
["Other Applications",0,"-"]
["Applications with processing agreements are not included in the following figures."]
[null,"Total Number of Decisions","Proportion of Decisions","Average Time (Weeks)",null,null,null,null,null,"check sums to total"]
["All Major Developments",2,null,24.142857142857142,null,null,null,null,null,"OK","OK",{"$error":"#VALUE!"}]
["Without Legal Agreement",2,1,24.142857142857142]
["With Legal Agreement",0,0,"-"]
[null,null,null,null,null,null,null,null,null,"OK"]
["All Local Developments",147,null,10.43731778425656,null,null,null,null,null,"OK","OK","OK"]
["Without Legal Agreement",137,0.93197278911564629,8.2867570385818556]
["With Legal Agreement",10,6.8027210884353748E-2,39.9]
["Local: less than 2 months",114,0.77551020408163263,6.0062656641604013,null,null,null,null,null,"OK","OK","OK"]
["Local: more than 2 months",33,0.22448979591836735,25.744588744588746]
[]
["All Local developments (non-householder)",79,null,14.613019891500903,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",51,0.64556962025316456,6.9075630252100835]
["Local: more than 2 months",28,0.35443037974683544,28.647959183673468]
[]
["Householder developments",68,null,5.5861344537815123,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",63,0.92647058823529416,5.2766439909297054]
["Local: more than 2 months",5,7.3529411764705885E-2,9.4857142857142858]
[]
["Housing Developments - Major",1,null,19.285714285714285]
[]
["Housing Developments - Local",19,null,24.488721804511279,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",9,0.47368421052631576,7.3174603174603172]
["Local: more than 2 months",10,0.52631578947368418,39.942857142857143]
[]
["Business & Industry - Major",1,null,29]
[]
["Business & Industry - Local",12,null,14.988095238095239,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",8,0.66666666666666663,6.9642857142857144]
["Local: more than 2 months",4,0.33333333333333331,31.035714285714285]
[]
["Other developments - Major",0,null,"-",null,null,null,null,null," "]
[]
["Other developments - Local",43,null,10.325581395348836,null,null,null,null,null,"OK","OK","OK"]
["Local: less than 2 months",31,0.72093023255813948,6.8018433179723496]
["Local: more than 2 months",12,0.27906976744186046,19.428571428571427]
[]
["EIA Developments",0,null,"-"]
["Other Consents",47,null,7.6565349544072943]
[]
["Decision Making: Applications subject to"]
["Planning/Legal Agreements",10,null,39.9]
["Local Reviews",2,null,5.5714285714285712,null,null,null,null,null,"Check local review totals"]
[null,null,null,null,null,null,null,null,null,"OK"]
["Decision Making: Local Reviews and Appeals"]
[]
[null,"Total number of decisions","Original decision upheld (%)"]
["Local Reviews",2,1]
["Appeals to Scottish Ministers2",9,0.55600000000000005]
[]
["Enforcement Activity"]
[]
[null,"Number"]
["Cases Taken Up",89]
["Notices Served",9]
["Reports to Procurator Fiscal",0]
["Prosecutions",0]
["Number of breaches resolved",91]
["Approved and Delegated"]
[]
["Percentage Approved",0.86111111111111116,null,null,null,null,null,null,"Approved",155,180,"Total Applications less N17"]
["Percentage Delegated",0.95477386934673369,null,null,null,null,null,null,"Delegated",190,199,"Total Applications"]
[null,null,null,null,null,null,null,null,null,null,214,"applications received"]
["1. For a full description of the categories in this analysis please see NOTES page."]
["2. Cases where the decision was recalled and made by Ministers are not included in these figures."]
["3. Time has been removed from the decision time for 13 applications where delays were outwith the control of the local authority."]